{"id":108761,"date":"2023-08-01T02:29:23","date_gmt":"2023-08-01T05:29:23","guid":{"rendered":"https:\/\/infoecos.com.ar\/?p=108761"},"modified":"2023-08-02T01:11:32","modified_gmt":"2023-08-02T04:11:32","slug":"lo-prometido-es-deuda-nos-metemos-en-las-paso","status":"publish","type":"post","link":"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/","title":{"rendered":"Lo prometido es deuda: nos metemos en las \u00abPASO\u00bb"},"content":{"rendered":"\n<p><strong>Un poco mucho, quiz\u00e1:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Buena promoci\u00f3n logr\u00f3 el senador provincial, Juanci Mart\u00ednez, que aspira a conducir los destinos de Rivadavia. Con una verdad a medias, el dirigente alcanz\u00f3 repercusi\u00f3n en toda la secci\u00f3n electoral con la incorporaci\u00f3n del arquitecto Jos\u00e9 Carabelli a su staff de colaboradores y anunciar, si llega a ser elegido, la creaci\u00f3n de una Secretar\u00eda de Vivienda y H\u00e1bitat. Carabelli, que aparece con Mart\u00ednez (ver foto) en la ampliaci\u00f3n urbana de Trenque Lauquen fue un colaborador directo de Jorge Barracchia cuando \u00e9ste asumi\u00f3 el municipio, pero el verdadero ide\u00f3logo de ese espacio que se ha convertido en la Ciudad Sat\u00e9lite que se imagin\u00f3 en un comienzo, fue precisamente el mandatario comunal fallecido en el 2011 y acompa\u00f1ado en primera instancia por el Arquitecto Jorge Prieto. No dej\u00f3 de ser el profesional mencionado un abnegado trabajador en pos de llevar adelante esa realizaci\u00f3n, pero de ah\u00ed a que se le coloque el mote de ide\u00f3logo hay importante diferencia. Carabelli aparece en la fotograf\u00eda distribuida por el equipo de prensa del legislador con un cartel detr\u00e1s que hace referencia a 50 viviendas de un plan bonaerense. El mismo se realiza con la administraci\u00f3n de la AMOC que conduce el gremialista de la UOCRA, N\u00e9stor Rodr\u00edguez, de muy buena sinton\u00eda con el Instituto de la Vivienda e incluso todos los gobiernos municipales de Trenque Lauquen. <\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli.jpg\" alt=\"\" class=\"wp-image-108762\" width=\"497\" height=\"331\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli.jpg 1368w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli-800x533.jpg 800w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli-768x512.jpg 768w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli-1024x683.jpg 1024w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli-675x450.jpg 675w\" sizes=\"(max-width: 497px) 100vw, 497px\" \/><figcaption class=\"wp-element-caption\">Carabelli y Mart\u00ednez<\/figcaption><\/figure>\n\n\n\n<p><strong>Con prudencia, pero confianza en las huestes de la l\u00ednea del oficialismo trenquelauquense para el 13 de Septiembre<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Me cont\u00f3 un \u00abpajarito\u00bb que suele posarse en el interior de las sedes partidarias que el radicalismo de Trenque Lauquen viene reuni\u00e9ndose en forma permanente y que se lo nota prudente, pero confiado a Francisco Recoulat para las elecciones del pr\u00f3ximo 13 de Diciembre. El actual presidente del bloque de concejales de Juntos por el Cambio, qui\u00e9n est\u00e1 acompa\u00f1ado por un lote interesante de dirigentes, se re\u00fane con los vecinos en el marco de la campa\u00f1a y la recepci\u00f3n es \u00abbuena\u00bb. Este lunes, cumpliendo con el pedido que hicimos nos hicieron saber lo siguiente:<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center\"><strong><em>El precandidato a Intendente del Distrito de Trenque Lauquen de Juntos por el<br>Cambio, Francisco Recoulat, presentar\u00e1 a los integrantes de la lista y el equipo<br>que lo acompa\u00f1a para las pr\u00f3ximas elecciones PASO en un acto organizado en<br>el subcomit\u00e9 de la UCR de 30 de agosto este pr\u00f3ximo mi\u00e9rcoles a las 20,30<br>horas.<\/em><\/strong><br><strong>Al acto est\u00e1 previsto que asistan los precandidatos a concejales y consejeros<br>escolares de la lista que propone a Francisco Recoulat como Intendente, y<br>tambi\u00e9n estar\u00e1 presente el precandidato a diputado provincial Valent\u00edn Miranda,<br>quien encabeza la n\u00f3mina de la Cuarta Secci\u00f3n Electoral representando a<br>nuestro distrito.<\/strong><br><strong>\u201cEs una oportunidad para seguir estando cerca de la comunidad de 30 de<br>Agosto como lo venimos haciendo desde hace ya tiempo, ocup\u00e1ndonos de las<br>cuestiones que preocupan a los vecinos y planteando ejes de acci\u00f3n para que<br>la localidad tenga la mejor calidad de vida en materia de salud, infraestructura,<br>empleo, seguridad, educaci\u00f3n y deporte\u201d, manifest\u00f3 Francisco Recoulat en la<br>previa del acto al que est\u00e1n invitadas todas las familias de 30 de Agosto.<\/strong><br><strong>Para Francisco Recoulat, la presencia en la localidad \u201csiempre es muy<br>importante porque podemos conocer de primera mano de los vecinos los temas<br>que les interesan, pero por sobre todas las cosas podemos pensar en c\u00f3mo<br>alcanzar logros y anhelos, muchos de ellos largamente esperados, algo que en<br>la actual gesti\u00f3n se viene concretando con obras importantes en cuanto al<br>aporte de fondos, pero tambi\u00e9n al impacto social, haciendo de 30 de Agosto<br>una ciudad en constante crecimiento y desarrollo\u201d.<\/strong><br><strong>La invitaci\u00f3n para conocer las propuestas y los ejes de gesti\u00f3n est\u00e1 hecha para<br>el mi\u00e9rcoles 2 de agosto a las 20,30 horas en el subcomit\u00e9 de la UCR, ubicado<br>en Laprida N\u00ba 71.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/30-DE-AGOSTO-2-1-1-901x1600.png\" alt=\"\" class=\"wp-image-108764\" width=\"393\" height=\"697\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/30-DE-AGOSTO-2-1-1-901x1600.png 901w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/30-DE-AGOSTO-2-1-1-768x1364.png 768w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/30-DE-AGOSTO-2-1-1-865x1536.png 865w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/30-DE-AGOSTO-2-1-1-1153x2048.png 1153w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/30-DE-AGOSTO-2-1-1-1024x1819.png 1024w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/30-DE-AGOSTO-2-1-1.png 1818w\" sizes=\"(max-width: 393px) 100vw, 393px\" \/><\/figure>\n\n\n\n<p><strong>Precandidato y una especie de vocero, hasta de lujo<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El precandidato a concejal en primer t\u00e9rmino por la lista Celeste de Uni\u00f3n por la Patria se ha convertido en vocero de lujo, al menos para este \u00abHijo de&#8230;.\u00bb que se entera de todo y tambi\u00e9n anda por las calles, sin ser advertido. Hace unas horas transmiti\u00f3 su satisfacci\u00f3n porque que les hab\u00edan concedido la posibilidad de presentar en el cuarto oscuro la boleta con Massa y Grabois a la cabeza, respectivamente. Hace unas horas, vimos a Sotullo como caminaba apresuradamente por la Plaza San Mart\u00edn, repartiendo la boleta. Lo segu\u00eda muy de cerca, una de las ide\u00f3logas de este armado electoral dentro del oficialismo nacional y provincial, M\u00f3nica Est\u00e9vez. Ella viene mostr\u00e1ndose muy activa y sonriente, transmitiendo optimismo. El actual titular del PAMI Trenque Lauquen, no nos transmite opiniones, ni tampoco hace ninguna declaraci\u00f3n. Imagino que es para no agitar las aguas de ning\u00fan lado. Sabe de estas lides. No hay que olvidarse que fue por \u00absu cuenta\u00bb cuando arranc\u00f3 y despu\u00e9s se convirti\u00f3 en uno de los competidores contra Miguel Fern\u00e1ndez, en las generales del 2015. <\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/boletasconmassaygrabois.jpg\" alt=\"\" class=\"wp-image-108765\" width=\"463\" height=\"347\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/boletasconmassaygrabois.jpg 1024w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/boletasconmassaygrabois-800x600.jpg 800w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/boletasconmassaygrabois-768x576.jpg 768w\" sizes=\"(max-width: 463px) 100vw, 463px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mart\u00edn me env\u00eda una foto donde el photoshop a funcionado a pleno. Nunca Larrosa ha aparecido tan prolijo y \u00e9l tan bien peinado.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/larrosasotullo.jpg\" alt=\"\" class=\"wp-image-108766\" width=\"462\" height=\"759\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/larrosasotullo.jpg 914w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/larrosasotullo-487x800.jpg 487w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/larrosasotullo-768x1262.jpg 768w\" sizes=\"(max-width: 462px) 100vw, 462px\" \/><\/figure>\n\n\n\n<p><strong>Empresaria e institucional: <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gracias a los lectores que corrijen, pero lamento decirles que las nuevas instalaciones de AFIP estar\u00e1n en un inmueble que se construye en la intersecci\u00f3n de Garc\u00eda Salinas y Freyre. La altura de la estaci\u00f3n de servicios que ser\u00e1 vecina al ente recaudador figura al 1400 de la avenida mencionada en primer t\u00e9rmino, y la compa\u00f1\u00eda Antares, al 1440. Acepto la correci\u00f3n sobre donde funciona actualmente la Administraci\u00f3n, cuyo titular es Carlos Castagneto y la he corregido. Es un inmueble ubicado sobre la calle Roca, entre 25 de Mayo y Mariano Moreno. Como suelo escribir casi dormido, hab\u00eda puesto calle San Mart\u00edn en el informe que ahora est\u00e1 publicado entre las noticias del panel m\u00e1s reducido en fotos y t\u00edtulos.<\/li>\n<\/ul>\n\n\n\n<p><strong>Bajo el t\u00edtulo: EL HIJO DE CUCA X DOS<\/strong><\/p>\n\n\n\n<p><strong>Confirman a Infoecos que la AFIP ya tiene arrendado un edificio que se construye en Garc\u00eda Salinas y Freyre<\/strong>.<\/p>\n\n\n\n<p>Actualmente el ente recaudador desarrolla el trabajo en un edificio de amplias proporciones sobre la calle Roca, entre Mariano Moreno y 25 de Mayo. No es, para buen n\u00famero de vecinos, ninguna novedad. En este tipo de cosas la \u00abchusma\u00bb comunitaria se pone en marcha r\u00e1pidamente y saca cuentas sobre qui\u00e9n es el due\u00f1o del inmueble que se alquil\u00f3, pero especialmente cuanto cobrar\u00e1 de alquiler.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/fotogarciasalins.jpg\" alt=\"\" class=\"wp-image-108767\" width=\"414\" height=\"276\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/fotogarciasalins.jpg 1024w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/fotogarciasalins-800x534.jpg 800w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/fotogarciasalins-768x512.jpg 768w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/fotogarciasalins-675x450.jpg 675w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gracias los que recogieron el convite y nos enviaron informaci\u00f3n que no se intercambia por pauta. ideolog\u00eda o sobre. Gracias al equipo de Mart\u00ednez, a los colaboradores del Ingeniero Recoulat y a Mart\u00edn Sotullo de Uni\u00f3n por la Patria<\/p>\n","protected":false},"author":2,"featured_media":108762,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1643],"tags":[8491],"class_list":["post-108761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inferior16","tag-el-hijo-de-cuca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lo prometido es deuda: nos metemos en las &quot;PASO&quot; - Infoecos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo prometido es deuda: nos metemos en las &quot;PASO&quot; - Infoecos\" \/>\n<meta property=\"og:description\" content=\"Gracias los que recogieron el convite y nos enviaron informaci\u00f3n que no se intercambia por pauta. ideolog\u00eda o sobre. Gracias al equipo de Mart\u00ednez, a los colaboradores del Ingeniero Recoulat y a Mart\u00edn Sotullo de Uni\u00f3n por la Patria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/\" \/>\n<meta property=\"og:site_name\" content=\"Infoecos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-01T05:29:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-02T04:11:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1368\" \/>\n\t<meta property=\"og:image:height\" content=\"912\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Matheus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infoecos\" \/>\n<meta name=\"twitter:site\" content=\"@infoecos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Matheus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/\"},\"author\":{\"name\":\"Jorge Matheus\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\"},\"headline\":\"Lo prometido es deuda: nos metemos en las \u00abPASO\u00bb\",\"datePublished\":\"2023-08-01T05:29:23+00:00\",\"dateModified\":\"2023-08-02T04:11:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/\"},\"wordCount\":1114,\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli.jpg\",\"keywords\":[\"El Hijo de Cuca\"],\"articleSection\":[\"Bloque inferior - 16\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/\",\"name\":\"Lo prometido es deuda: nos metemos en las \\\"PASO\\\" - Infoecos\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli.jpg\",\"datePublished\":\"2023-08-01T05:29:23+00:00\",\"dateModified\":\"2023-08-02T04:11:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/#primaryimage\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli.jpg\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli.jpg\",\"width\":1368,\"height\":912},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/infoecos.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo prometido es deuda: nos metemos en las \u00abPASO\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/infoecos.com.ar\/#website\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"name\":\"Infoecos\",\"description\":\"Noticias de trenque lauquen y la zona\",\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"alternateName\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/infoecos.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/infoecos.com.ar\/#organization\",\"name\":\"Infoecos\",\"alternateName\":\"Noticias\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"width\":374,\"height\":90,\"caption\":\"Infoecos\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\",\"https:\/\/x.com\/infoecos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\",\"name\":\"Jorge Matheus\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo prometido es deuda: nos metemos en las \"PASO\" - Infoecos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/","og_locale":"es_ES","og_type":"article","og_title":"Lo prometido es deuda: nos metemos en las \"PASO\" - Infoecos","og_description":"Gracias los que recogieron el convite y nos enviaron informaci\u00f3n que no se intercambia por pauta. ideolog\u00eda o sobre. Gracias al equipo de Mart\u00ednez, a los colaboradores del Ingeniero Recoulat y a Mart\u00edn Sotullo de Uni\u00f3n por la Patria","og_url":"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/","og_site_name":"Infoecos","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063200290284","article_published_time":"2023-08-01T05:29:23+00:00","article_modified_time":"2023-08-02T04:11:32+00:00","og_image":[{"width":1368,"height":912,"url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli.jpg","type":"image\/jpeg"}],"author":"Jorge Matheus","twitter_card":"summary_large_image","twitter_creator":"@infoecos","twitter_site":"@infoecos","twitter_misc":{"Escrito por":"Jorge Matheus","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/#article","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/"},"author":{"name":"Jorge Matheus","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191"},"headline":"Lo prometido es deuda: nos metemos en las \u00abPASO\u00bb","datePublished":"2023-08-01T05:29:23+00:00","dateModified":"2023-08-02T04:11:32+00:00","mainEntityOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/"},"wordCount":1114,"publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli.jpg","keywords":["El Hijo de Cuca"],"articleSection":["Bloque inferior - 16"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/","url":"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/","name":"Lo prometido es deuda: nos metemos en las \"PASO\" - Infoecos","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/#primaryimage"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli.jpg","datePublished":"2023-08-01T05:29:23+00:00","dateModified":"2023-08-02T04:11:32+00:00","breadcrumb":{"@id":"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/#primaryimage","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli.jpg","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli.jpg","width":1368,"height":912},{"@type":"BreadcrumbList","@id":"https:\/\/infoecos.com.ar\/index.php\/lo-prometido-es-deuda-nos-metemos-en-las-paso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoecos.com.ar\/"},{"@type":"ListItem","position":2,"name":"Lo prometido es deuda: nos metemos en las \u00abPASO\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/infoecos.com.ar\/#website","url":"https:\/\/infoecos.com.ar\/","name":"Infoecos","description":"Noticias de trenque lauquen y la zona","publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"alternateName":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoecos.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoecos.com.ar\/#organization","name":"Infoecos","alternateName":"Noticias","url":"https:\/\/infoecos.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","width":374,"height":90,"caption":"Infoecos"},"image":{"@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063200290284","https:\/\/x.com\/infoecos"]},{"@type":"Person","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191","name":"Jorge Matheus","url":"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/"}]}},"featured_image_urls":{"full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli.jpg",1368,912,false],"thumbnail":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli-300x150.jpg",300,150,true],"medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli-800x533.jpg",800,533,true],"medium_large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli-768x512.jpg",640,427,true],"large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli.jpg",640,427,false],"1536x1536":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli.jpg",1368,912,false],"2048x2048":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli.jpg",1368,912,false],"covernews-slider-full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli.jpg",1073,715,false],"covernews-slider-center":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli-936x897.jpg",522,500,true],"covernews-featured":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli-1024x683.jpg",1024,683,true],"covernews-medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli-720x380.jpg",540,285,true],"covernews-medium-square":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2023\/08\/martinezycarabelli-675x450.jpg",375,250,true]},"author_info":{"info":["Jorge Matheus"]},"category_info":"<a href=\"https:\/\/infoecos.com.ar\/index.php\/category\/inferior16\/\" rel=\"category tag\">Bloque inferior - 16<\/a>","tag_info":"Bloque inferior - 16","comment_count":"0","_links":{"self":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/108761"}],"collection":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=108761"}],"version-history":[{"count":1,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/108761\/revisions"}],"predecessor-version":[{"id":108768,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/108761\/revisions\/108768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media\/108762"}],"wp:attachment":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=108761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=108761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=108761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}