{"id":119138,"date":"2024-02-16T01:58:25","date_gmt":"2024-02-16T04:58:25","guid":{"rendered":"https:\/\/infoecos.com.ar\/?p=119138"},"modified":"2024-02-18T11:44:40","modified_gmt":"2024-02-18T14:44:40","slug":"10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales","status":"publish","type":"post","link":"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/","title":{"rendered":"10 acuerdos, 17 pedidos y 4 propuestas de trabajo en las 51\u00b0 Jornadas Trigueras Nacionales"},"content":{"rendered":"\n<p>Se desarrollo este jueves 15 la 10\u00ba Mesa Nacional del Trigo,&nbsp; dada en el marco de las 51\u00b0 Jornadas Trigueras Nacionales y la 68\u00b0 Fiesta Nacional del Trigo, de la ciudad cordobesa de Leones.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-260.png\" alt=\"\" class=\"wp-image-119139\" width=\"444\" height=\"333\"\/><\/figure>\n\n\n\n<p>El conclave trigero reuni\u00f3 a autoridades de siete provincias productivas, una veintena de intendentes y representantes de m\u00e1s de 30 entidades de toda la cadena triguera del pa\u00eds, que compartieron informaci\u00f3n y proyecciones sectoriales, indispensables para definir los ejes de trabajo.<\/p>\n\n\n\n<p>Al cierre de la 10\u00ba edici\u00f3n de la Mesa, se firm\u00f3 un acta en la cual se expresan los principales ejes que se abordaron; los acuerdos, pedidos y propuestas para trabajar durante el a\u00f1o y en las agendas futuras.<\/p>\n\n\n\n<p>Puntualmente, se expresaron 10 acuerdos, 17 pedidos y 4 propuestas de trabajo.<\/p>\n\n\n\n<p><strong>Puntos de Acuerdo<\/strong><\/p>\n\n\n\n<p>1. La participaci\u00f3n comprometida de diversas instituciones del sector p\u00fablico y privado, alcanzando a todos los sectores de la cadena agroindustrial del cultivo del trigo permite construir entre todos una agenda de trabajo que apunte a robustecer y ampliar el horizonte de la pol\u00edtica triguera para los pr\u00f3ximos a\u00f1os, aspirando a que estos lineamientos sean un compromiso de una pol\u00edtica de Estado y Una Pol\u00edtica empresaria a largo plazo y de alto impacto para la sociedad en su comuni\u00f3n con lo urbano y rural.<\/p>\n\n\n\n<p>2. Marca Pa\u00eds de TrigAR.<\/p>\n\n\n\n<p>3. Incentivar la producci\u00f3n del Trigo en esta campa\u00f1a. (24\/25)<\/p>\n\n\n\n<p>4. Los equilibrios se logran con normas claras. Por lo cual solicitamos avanzar en las propuestas legislativas que contribuyan a toda la Cadena.<\/p>\n\n\n\n<p>Ley de Semillas y recursos fitogen\u00e9ticos estrat\u00e9gicos (bancos de germoplasma), Promoci\u00f3n de Fertilizantes, Plan Agroindustrial.<\/p>\n\n\n\n<p>5. Investigaci\u00f3n, Desarrollo e Innovaci\u00f3n.<\/p>\n\n\n\n<p>6. Generar un espacio desde INASE para trabajar el UPOV o generar un espacio superador.<\/p>\n\n\n\n<p>7. Compromiso desde la regi\u00f3n centro sumando a dem\u00e1s provincias, para retomar el congreso internacional TRIGAR.<\/p>\n\n\n\n<p>8. Solicitar el fortalecimiento de las instituciones de investigaci\u00f3n en relaci\u00f3n a la cadena de Trigo (INTA, Conicet, Universidades, CyT, otros organismos).<\/p>\n\n\n\n<p>9. Pol\u00edtica de Calidad y Comercial. Trabajar en comercio internacional por medio de la colaboraci\u00f3n p\u00fablica privada, trabajando en funci\u00f3n de la demanda. Granos, harinas, pastas, productos y derivados de la cadena.<\/p>\n\n\n\n<p>Trabajar y mejorar procesos de trazabilidad y transparencia.<\/p>\n\n\n\n<p>Trabajar en el abastecimiento del Mercado Interno.<\/p>\n\n\n\n<p>Fomentar acciones para disminuir el riesgo, como seguros<\/p>\n\n\n\n<p>Comunicaci\u00f3n estrat\u00e9gica (beneficios del trigo y su transformaci\u00f3n) y Acciones en Sostenibilidad.<\/p>\n\n\n\n<p>10. Visi\u00f3n sist\u00e9mica del trigo, Posicionar la Cadena dentro de la Bioeconom\u00eda, Buenas Pr\u00e1cticas Agropecuarias, simplificaci\u00f3n del esquema tributario y de requerimientos, comunicaci\u00f3n unificada de la cadena, potenciar la visi\u00f3n de la Bioeconom\u00eda, promoci\u00f3n de las exportaciones y el valor agregado del trigo, infraestructura e innovaci\u00f3n institucional.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png\" alt=\"\" class=\"wp-image-119140\" width=\"524\" height=\"295\"\/><\/figure>\n\n\n\n<p><strong>Listado de pedidos<\/strong><\/p>\n\n\n\n<p>1. Eliminar los derechos de exportaci\u00f3n que desalientan la producci\u00f3n y el compromiso de no intervenci\u00f3n del mercado (entidades agropecuarias-sector privado).<\/p>\n\n\n\n<p>2. Tomar como tema de comunicaci\u00f3n la Huella de Carbono.<\/p>\n\n\n\n<p>3. Generar 2 reuniones al a\u00f1o (como propuesta de fecha es en el remate anual de trigo).<\/p>\n\n\n\n<p>4. Promover a nivel nacional para solucionar problemas con lo que respecta a la log\u00edstica, infraestructura, caminos, energ\u00eda en todas las provincias.<\/p>\n\n\n\n<p>5. Generar nomencladores para poder vender los distintos tipos de trigo.<\/p>\n\n\n\n<p>6. Potenciar la comunicaci\u00f3n del mapeo de calidad de trigo en Argentina www.trigoargentino.com.ar<\/p>\n\n\n\n<p>7. I+D+I, redes de conocimiento en conjunto con la academia, capacitaci\u00f3n de comunicadores (AUDEAS).<\/p>\n\n\n\n<p>8. Quitar la reglamentaci\u00f3n del Banco Central sobre el stock en producci\u00f3n (Resoluci\u00f3n 7600).<\/p>\n\n\n\n<p>9. Todo volumen exportado extra MERCOSUR al que hoy no se exporta, que no tenga retenciones harina de trigo (FAIM y CIM).<\/p>\n\n\n\n<p>10. Evaluar en lo tributario el costo impositivo en cada eslab\u00f3n de la cadena. Evaluar distorsiones de la cadena contribuyendo a la transparencia del mercado. (sector privado) (FAIM y CIM).<\/p>\n\n\n\n<p>11. Generar financiamiento para toda la cadena.<\/p>\n\n\n\n<p>12. Previsibilidad, eliminar los mecanismos de intervenciones distorsivos formales e informales. rechazamos enf\u00e1ticamente la formaci\u00f3n de fideicomisos o herramientas similares. No queremos desdoblamiento cambiario. (Entidades agropecuarias)<\/p>\n\n\n\n<p>13. Trabajar y mejorar procesos de trazabilidad y transparencia, solicitando urgente intervenci\u00f3n del estado nacional para frenar la marginalidad.<\/p>\n\n\n\n<p>14. Impulsar un proyecto de ley para el uso de semilla certificada a trav\u00e9s de una doble deducci\u00f3n de ganancias y la al\u00edcuota de IVA igual al producto (pedido sector privado FAA y Aaprotrigo)<\/p>\n\n\n\n<p>15. Adopci\u00f3n de un Programa de Buenas Practicas Agropecuarias a nivel nacional.<\/p>\n\n\n\n<p>16. Trazabilidad de material gen\u00e9tico modificado (GMO)<\/p>\n\n\n\n<p>17. Promoci\u00f3n de tecnolog\u00eda para los productores en zonas marginales (riego, conservaci\u00f3n de suelos, etc).<\/p>\n\n\n\n<p><strong>Propuestas de trabajo<\/strong><\/p>\n\n\n\n<p>1. Aunar esfuerzos desde lo p\u00fablico y privado para la realizaci\u00f3n del Congreso Internacional de TRIGAR.<\/p>\n\n\n\n<p>2. Mesa de trabajo en 180 d\u00edas para evaluar los resultados con indicadores, en el marco del remate de trigo.<\/p>\n\n\n\n<p>3.Trabajo en relaci\u00f3n a ley de semillas, UPOV o propuesta superadora.<\/p>\n\n\n\n<p>4.Fortalecimiento en comunicaci\u00f3n de la cadena.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al cierre de la 10\u00ba edici\u00f3n de la Mesa, se firm\u00f3 un acta en la cual se expresan los principales ejes que se abordaron<\/p>\n","protected":false},"author":2,"featured_media":119140,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[7373],"class_list":["post-119138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inferior5","tag-leones-cordoba"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>10 acuerdos, 17 pedidos y 4 propuestas de trabajo en las 51\u00b0 Jornadas Trigueras Nacionales - Infoecos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 acuerdos, 17 pedidos y 4 propuestas de trabajo en las 51\u00b0 Jornadas Trigueras Nacionales - Infoecos\" \/>\n<meta property=\"og:description\" content=\"Al cierre de la 10\u00ba edici\u00f3n de la Mesa, se firm\u00f3 un acta en la cual se expresan los principales ejes que se abordaron\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/\" \/>\n<meta property=\"og:site_name\" content=\"Infoecos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-16T04:58:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-18T14:44:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jorge Matheus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infoecos\" \/>\n<meta name=\"twitter:site\" content=\"@infoecos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Matheus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/\"},\"author\":{\"name\":\"Jorge Matheus\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\"},\"headline\":\"10 acuerdos, 17 pedidos y 4 propuestas de trabajo en las 51\u00b0 Jornadas Trigueras Nacionales\",\"datePublished\":\"2024-02-16T04:58:25+00:00\",\"dateModified\":\"2024-02-18T14:44:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/\"},\"wordCount\":837,\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png\",\"keywords\":[\"LEONES (C\u00d3RDOBA)\"],\"articleSection\":[\"Bloque inferior - 5\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/\",\"name\":\"10 acuerdos, 17 pedidos y 4 propuestas de trabajo en las 51\u00b0 Jornadas Trigueras Nacionales - Infoecos\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png\",\"datePublished\":\"2024-02-16T04:58:25+00:00\",\"dateModified\":\"2024-02-18T14:44:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/#primaryimage\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png\",\"width\":768,\"height\":432},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/infoecos.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 acuerdos, 17 pedidos y 4 propuestas de trabajo en las 51\u00b0 Jornadas Trigueras Nacionales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/infoecos.com.ar\/#website\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"name\":\"Infoecos\",\"description\":\"Noticias de trenque lauquen y la zona\",\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"alternateName\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/infoecos.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/infoecos.com.ar\/#organization\",\"name\":\"Infoecos\",\"alternateName\":\"Noticias\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"width\":374,\"height\":90,\"caption\":\"Infoecos\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\",\"https:\/\/x.com\/infoecos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\",\"name\":\"Jorge Matheus\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 acuerdos, 17 pedidos y 4 propuestas de trabajo en las 51\u00b0 Jornadas Trigueras Nacionales - Infoecos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/","og_locale":"es_ES","og_type":"article","og_title":"10 acuerdos, 17 pedidos y 4 propuestas de trabajo en las 51\u00b0 Jornadas Trigueras Nacionales - Infoecos","og_description":"Al cierre de la 10\u00ba edici\u00f3n de la Mesa, se firm\u00f3 un acta en la cual se expresan los principales ejes que se abordaron","og_url":"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/","og_site_name":"Infoecos","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063200290284","article_published_time":"2024-02-16T04:58:25+00:00","article_modified_time":"2024-02-18T14:44:40+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png","type":"image\/png"}],"author":"Jorge Matheus","twitter_card":"summary_large_image","twitter_creator":"@infoecos","twitter_site":"@infoecos","twitter_misc":{"Escrito por":"Jorge Matheus","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/#article","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/"},"author":{"name":"Jorge Matheus","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191"},"headline":"10 acuerdos, 17 pedidos y 4 propuestas de trabajo en las 51\u00b0 Jornadas Trigueras Nacionales","datePublished":"2024-02-16T04:58:25+00:00","dateModified":"2024-02-18T14:44:40+00:00","mainEntityOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/"},"wordCount":837,"publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png","keywords":["LEONES (C\u00d3RDOBA)"],"articleSection":["Bloque inferior - 5"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/","url":"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/","name":"10 acuerdos, 17 pedidos y 4 propuestas de trabajo en las 51\u00b0 Jornadas Trigueras Nacionales - Infoecos","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/#primaryimage"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png","datePublished":"2024-02-16T04:58:25+00:00","dateModified":"2024-02-18T14:44:40+00:00","breadcrumb":{"@id":"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/#primaryimage","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png","width":768,"height":432},{"@type":"BreadcrumbList","@id":"https:\/\/infoecos.com.ar\/index.php\/10-acuerdos-17-pedidos-y-4-propuestas-de-trabajo-en-las-51-jornadas-trigueras-nacionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoecos.com.ar\/"},{"@type":"ListItem","position":2,"name":"10 acuerdos, 17 pedidos y 4 propuestas de trabajo en las 51\u00b0 Jornadas Trigueras Nacionales"}]},{"@type":"WebSite","@id":"https:\/\/infoecos.com.ar\/#website","url":"https:\/\/infoecos.com.ar\/","name":"Infoecos","description":"Noticias de trenque lauquen y la zona","publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"alternateName":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoecos.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoecos.com.ar\/#organization","name":"Infoecos","alternateName":"Noticias","url":"https:\/\/infoecos.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","width":374,"height":90,"caption":"Infoecos"},"image":{"@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063200290284","https:\/\/x.com\/infoecos"]},{"@type":"Person","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191","name":"Jorge Matheus","url":"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/"}]}},"featured_image_urls":{"full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png",768,432,false],"thumbnail":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261-300x150.png",300,150,true],"medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png",768,432,false],"medium_large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png",640,360,false],"large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png",640,360,false],"1536x1536":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png",768,432,false],"2048x2048":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png",768,432,false],"covernews-slider-full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png",768,432,false],"covernews-slider-center":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png",768,432,false],"covernews-featured":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261.png",768,432,false],"covernews-medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261-720x380.png",540,285,true],"covernews-medium-square":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/02\/image-261-675x432.png",391,250,true]},"author_info":{"info":["Jorge Matheus"]},"category_info":"<a href=\"https:\/\/infoecos.com.ar\/index.php\/category\/inferior5\/\" rel=\"category tag\">Bloque inferior - 5<\/a>","tag_info":"Bloque inferior - 5","comment_count":"0","_links":{"self":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/119138"}],"collection":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=119138"}],"version-history":[{"count":2,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/119138\/revisions"}],"predecessor-version":[{"id":119326,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/119138\/revisions\/119326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media\/119140"}],"wp:attachment":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=119138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=119138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=119138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}