{"id":136127,"date":"2025-01-20T22:08:49","date_gmt":"2025-01-21T01:08:49","guid":{"rendered":"https:\/\/infoecos.com.ar\/?p=136127"},"modified":"2025-01-22T13:52:07","modified_gmt":"2025-01-22T16:52:07","slug":"van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi","status":"publish","type":"post","link":"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/","title":{"rendered":"Van a juicio el intendente de Florentino Ameghino, Nahuel Mittelbach y la Directora de Obras P\u00fablicas, Luz Foresi"},"content":{"rendered":"\n<p>La Justicia de Jun\u00edn<strong> <\/strong>elev\u00f3 a juicio la causa que investiga la muerte de seis personas en un pozo de cloacas en la localidad de Blaquier, distrito de Florentino Ameghino<strong>.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"992\" height=\"558\" src=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-259.png\" alt=\"\" class=\"wp-image-136128\" style=\"width:446px;height:auto\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-259.png 992w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-259-800x450.png 800w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-259-768x432.png 768w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/><\/figure>\n\n\n\n<p>La jueza subrogante del Juzgado de Garant\u00edas 1, Mar\u00eda Laura Durante, resolvi\u00f3 denegar los sobreseimientos del intendente Nahuel Mittelbach y de Luz Foresi. <\/p>\n\n\n\n<p>Se investiga las muertes de Ricardo Bottega, Alejandro Daniel Centeno, Juan Ram\u00f3n S\u00e1nchez, Juan Nicol\u00e1s S\u00e1nchez, Mateo Pellegrino y Carlos Rodolfo Renger, ocurridas el d\u00eda 15 de marzo de 2024<strong>.<\/strong>\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"586\" src=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-260.png\" alt=\"\" class=\"wp-image-136129\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-260.png 880w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-260-800x533.png 800w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-260-768x511.png 768w\" sizes=\"(max-width: 880px) 100vw, 880px\" \/><\/figure>\n\n\n\n<p>A Nahuel Mittelbach, se le imputa el delito de \u201cincumplimiento de los deberes de funcionario p\u00fablico\u201d, y a Foresi, \u201chomicidio culposo\u201d<strong>.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"970\" height=\"550\" src=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png\" alt=\"\" class=\"wp-image-136131\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png 970w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262-800x454.png 800w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262-768x435.png 768w\" sizes=\"(max-width: 970px) 100vw, 970px\" \/><\/figure>\n\n\n\n<p>El hecho se produjo durante la tarde del 15 de marzo cuando\u00a0un hombre, que hab\u00eda sido contratado por el municipio para hacer \u201ctareas de mantenimiento rutinario en el sistema de red cloacal\u201d, ingres\u00f3 a un pozo ubicado en un lugar llamado \u201cEl Cigarro\u201d, de 12 metros de profundidad, y no volvi\u00f3 a salir a la superficie. Otras cinco personas, entre ellos tres bomberos, intentaron rescatar al operario, pero todos fallecieron<strong>.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-261.png\" alt=\"\" class=\"wp-image-136130\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La jueza subrogante del Juzgado de Garant\u00edas 1, Mar\u00eda Laura Durante, resolvi\u00f3 denegar los sobreseimientos del intendente Nahuel Mittelbach y de Luz Foresi<\/p>\n","protected":false},"author":2,"featured_media":136131,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[10290],"class_list":["post-136127","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-entretenimiento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Van a juicio el intendente de Florentino Ameghino, Nahuel Mittelbach y la Directora de Obras P\u00fablicas, Luz Foresi - Infoecos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Van a juicio el intendente de Florentino Ameghino, Nahuel Mittelbach y la Directora de Obras P\u00fablicas, Luz Foresi - Infoecos\" \/>\n<meta property=\"og:description\" content=\"La jueza subrogante del Juzgado de Garant\u00edas 1, Mar\u00eda Laura Durante, resolvi\u00f3 denegar los sobreseimientos del intendente Nahuel Mittelbach y de Luz Foresi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/\" \/>\n<meta property=\"og:site_name\" content=\"Infoecos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-21T01:08:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-22T16:52:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png\" \/>\n\t<meta property=\"og:image:width\" content=\"970\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jorge Matheus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infoecos\" \/>\n<meta name=\"twitter:site\" content=\"@infoecos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Matheus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/\"},\"author\":{\"name\":\"Jorge Matheus\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\"},\"headline\":\"Van a juicio el intendente de Florentino Ameghino, Nahuel Mittelbach y la Directora de Obras P\u00fablicas, Luz Foresi\",\"datePublished\":\"2025-01-21T01:08:49+00:00\",\"dateModified\":\"2025-01-22T16:52:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/\"},\"wordCount\":199,\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png\",\"keywords\":[\"Entretenimiento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/\",\"name\":\"Van a juicio el intendente de Florentino Ameghino, Nahuel Mittelbach y la Directora de Obras P\u00fablicas, Luz Foresi - Infoecos\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png\",\"datePublished\":\"2025-01-21T01:08:49+00:00\",\"dateModified\":\"2025-01-22T16:52:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/#primaryimage\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png\",\"width\":970,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/infoecos.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Van a juicio el intendente de Florentino Ameghino, Nahuel Mittelbach y la Directora de Obras P\u00fablicas, Luz Foresi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/infoecos.com.ar\/#website\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"name\":\"Infoecos\",\"description\":\"Noticias de trenque lauquen y la zona\",\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"alternateName\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/infoecos.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/infoecos.com.ar\/#organization\",\"name\":\"Infoecos\",\"alternateName\":\"Noticias\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"width\":374,\"height\":90,\"caption\":\"Infoecos\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\",\"https:\/\/x.com\/infoecos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\",\"name\":\"Jorge Matheus\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Van a juicio el intendente de Florentino Ameghino, Nahuel Mittelbach y la Directora de Obras P\u00fablicas, Luz Foresi - Infoecos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/","og_locale":"es_ES","og_type":"article","og_title":"Van a juicio el intendente de Florentino Ameghino, Nahuel Mittelbach y la Directora de Obras P\u00fablicas, Luz Foresi - Infoecos","og_description":"La jueza subrogante del Juzgado de Garant\u00edas 1, Mar\u00eda Laura Durante, resolvi\u00f3 denegar los sobreseimientos del intendente Nahuel Mittelbach y de Luz Foresi","og_url":"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/","og_site_name":"Infoecos","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063200290284","article_published_time":"2025-01-21T01:08:49+00:00","article_modified_time":"2025-01-22T16:52:07+00:00","og_image":[{"width":970,"height":550,"url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png","type":"image\/png"}],"author":"Jorge Matheus","twitter_card":"summary_large_image","twitter_creator":"@infoecos","twitter_site":"@infoecos","twitter_misc":{"Escrito por":"Jorge Matheus","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/#article","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/"},"author":{"name":"Jorge Matheus","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191"},"headline":"Van a juicio el intendente de Florentino Ameghino, Nahuel Mittelbach y la Directora de Obras P\u00fablicas, Luz Foresi","datePublished":"2025-01-21T01:08:49+00:00","dateModified":"2025-01-22T16:52:07+00:00","mainEntityOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/"},"wordCount":199,"publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png","keywords":["Entretenimiento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/","url":"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/","name":"Van a juicio el intendente de Florentino Ameghino, Nahuel Mittelbach y la Directora de Obras P\u00fablicas, Luz Foresi - Infoecos","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/#primaryimage"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png","datePublished":"2025-01-21T01:08:49+00:00","dateModified":"2025-01-22T16:52:07+00:00","breadcrumb":{"@id":"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/#primaryimage","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png","width":970,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/infoecos.com.ar\/index.php\/van-a-juicio-el-intendente-de-florentino-ameghino-nahuel-mittelbach-y-la-directora-de-obras-publicas-luz-foresi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoecos.com.ar\/"},{"@type":"ListItem","position":2,"name":"Van a juicio el intendente de Florentino Ameghino, Nahuel Mittelbach y la Directora de Obras P\u00fablicas, Luz Foresi"}]},{"@type":"WebSite","@id":"https:\/\/infoecos.com.ar\/#website","url":"https:\/\/infoecos.com.ar\/","name":"Infoecos","description":"Noticias de trenque lauquen y la zona","publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"alternateName":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoecos.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoecos.com.ar\/#organization","name":"Infoecos","alternateName":"Noticias","url":"https:\/\/infoecos.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","width":374,"height":90,"caption":"Infoecos"},"image":{"@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063200290284","https:\/\/x.com\/infoecos"]},{"@type":"Person","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191","name":"Jorge Matheus","url":"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/"}]}},"featured_image_urls":{"full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png",970,550,false],"thumbnail":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262-300x150.png",300,150,true],"medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262-800x454.png",800,454,true],"medium_large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262-768x435.png",640,363,true],"large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png",640,363,false],"1536x1536":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png",970,550,false],"2048x2048":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png",970,550,false],"covernews-slider-full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png",970,550,false],"covernews-slider-center":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262-800x500.png",800,500,true],"covernews-featured":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262.png",970,550,false],"covernews-medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262-540x340.png",540,340,true],"covernews-medium-square":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2025\/01\/image-262-400x250.png",400,250,true]},"author_info":{"info":["Jorge Matheus"]},"category_info":"<a href=\"https:\/\/infoecos.com.ar\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","tag_info":"Sin categor\u00eda","comment_count":"0","_links":{"self":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/136127"}],"collection":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=136127"}],"version-history":[{"count":1,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/136127\/revisions"}],"predecessor-version":[{"id":136132,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/136127\/revisions\/136132"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media\/136131"}],"wp:attachment":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=136127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=136127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=136127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}