{"id":59167,"date":"2020-03-17T16:30:05","date_gmt":"2020-03-17T19:30:05","guid":{"rendered":"http:\/\/infoecos.com.ar\/?p=59167"},"modified":"2020-03-17T16:30:13","modified_gmt":"2020-03-17T19:30:13","slug":"coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel","status":"publish","type":"post","link":"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/","title":{"rendered":"Coronavirus: el bloque de concejales del Frente de Todos le pide al Departamento Ejecutivo de Trenque Lauquen que elabore alcohol en gel"},"content":{"rendered":"\n<p>El bloque del Frente para Todos del distrito de Trenque Lauquen present\u00f3 un proyecto de comunicaci\u00f3n en el Concejo Deliberante donde le solicita al Departamento Ejecutivo la elaboraci\u00f3n de alcohol en gel antis\u00e9ptico, gel antibacterial o gel limpiador bactericida.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img decoding=\"async\" src=\"http:\/\/infoecos.com.ar\/wp-content\/uploads\/407d98e1-fae2-4af8-8855-be109f37d5e5-460x307.jpg\" alt=\"\" class=\"wp-image-58057\"\/><figcaption>Sotullo Lanz, Mart\u00edn<\/figcaption><\/figure><\/div>\n\n\n\n<p>La medida requerida por los ediles se basa, fundamentalmente, que ante la expansi\u00f3n de la pandemia de coronavirus surgieron varios datos falsos sobre m\u00e9todos de prevenci\u00f3n y uno de los m\u00e1s difundidos fue la supuesta receta para fabricar alcohol en gel casero. En los considerandos se se\u00f1ala que \u00abespecialistas y la Organizaci\u00f3n Mundial de la Salud no recomiendan su producci\u00f3n hogare\u00f1a\u00bb. <\/p>\n\n\n\n<p>M\u00e1s adelante el proyecto de comunicaci\u00f3n del Frente de Todos apunta que la Municipalidad de Trenque Lauquen posee un laboratorio el cual abastece a los hospitales municipales de la ciudad cabecera y 30 de Agosto, a la sala sanitaria de Beruti y a los centros de referencia, contando con las condiciones necesarias para elaborar alcohol en gel, para luego proceder a su distribuci\u00f3n masiva en todo el distrito.<\/p>\n\n\n\n<p>En el art\u00edculo 2 del mencionado proyecto se pide la distribuci\u00f3n de las distintas variedades de alcohol con posibilidades de fabricar en todos los lugares de mayor concurrencia como colegios, instituciones, terminales de micros y a familias que por su vulnerabilidad no pueden adquirirlos.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El bloque del Frente para Todos del distrito de Trenque Lauquen present\u00f3 un proyecto de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":58057,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1613],"tags":[5],"class_list":["post-59167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia-secundaria","tag-trenque-lauquen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coronavirus: el bloque de concejales del Frente de Todos le pide al Departamento Ejecutivo de Trenque Lauquen que elabore alcohol en gel - Infoecos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus: el bloque de concejales del Frente de Todos le pide al Departamento Ejecutivo de Trenque Lauquen que elabore alcohol en gel - Infoecos\" \/>\n<meta property=\"og:description\" content=\"El bloque del Frente para Todos del distrito de Trenque Lauquen present\u00f3 un proyecto de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/\" \/>\n<meta property=\"og:site_name\" content=\"Infoecos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-17T19:30:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-17T19:30:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/407d98e1-fae2-4af8-8855-be109f37d5e5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Matheus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infoecos\" \/>\n<meta name=\"twitter:site\" content=\"@infoecos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Matheus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/\"},\"author\":{\"name\":\"Jorge Matheus\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\"},\"headline\":\"Coronavirus: el bloque de concejales del Frente de Todos le pide al Departamento Ejecutivo de Trenque Lauquen que elabore alcohol en gel\",\"datePublished\":\"2020-03-17T19:30:05+00:00\",\"dateModified\":\"2020-03-17T19:30:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/\"},\"wordCount\":252,\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Trenque Lauquen\"],\"articleSection\":[\"Noticia Secundaria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/\",\"name\":\"Coronavirus: el bloque de concejales del Frente de Todos le pide al Departamento Ejecutivo de Trenque Lauquen que elabore alcohol en gel - Infoecos\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-03-17T19:30:05+00:00\",\"dateModified\":\"2020-03-17T19:30:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/infoecos.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus: el bloque de concejales del Frente de Todos le pide al Departamento Ejecutivo de Trenque Lauquen que elabore alcohol en gel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/infoecos.com.ar\/#website\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"name\":\"Infoecos\",\"description\":\"Noticias de trenque lauquen y la zona\",\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"alternateName\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/infoecos.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/infoecos.com.ar\/#organization\",\"name\":\"Infoecos\",\"alternateName\":\"Noticias\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"width\":374,\"height\":90,\"caption\":\"Infoecos\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\",\"https:\/\/x.com\/infoecos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\",\"name\":\"Jorge Matheus\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coronavirus: el bloque de concejales del Frente de Todos le pide al Departamento Ejecutivo de Trenque Lauquen que elabore alcohol en gel - Infoecos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/","og_locale":"es_ES","og_type":"article","og_title":"Coronavirus: el bloque de concejales del Frente de Todos le pide al Departamento Ejecutivo de Trenque Lauquen que elabore alcohol en gel - Infoecos","og_description":"El bloque del Frente para Todos del distrito de Trenque Lauquen present\u00f3 un proyecto de...","og_url":"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/","og_site_name":"Infoecos","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063200290284","article_published_time":"2020-03-17T19:30:05+00:00","article_modified_time":"2020-03-17T19:30:13+00:00","og_image":[{"width":1170,"height":780,"url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/407d98e1-fae2-4af8-8855-be109f37d5e5.jpg","type":"image\/jpeg"}],"author":"Jorge Matheus","twitter_card":"summary_large_image","twitter_creator":"@infoecos","twitter_site":"@infoecos","twitter_misc":{"Escrito por":"Jorge Matheus","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/#article","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/"},"author":{"name":"Jorge Matheus","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191"},"headline":"Coronavirus: el bloque de concejales del Frente de Todos le pide al Departamento Ejecutivo de Trenque Lauquen que elabore alcohol en gel","datePublished":"2020-03-17T19:30:05+00:00","dateModified":"2020-03-17T19:30:13+00:00","mainEntityOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/"},"wordCount":252,"publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/#primaryimage"},"thumbnailUrl":"","keywords":["Trenque Lauquen"],"articleSection":["Noticia Secundaria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/","url":"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/","name":"Coronavirus: el bloque de concejales del Frente de Todos le pide al Departamento Ejecutivo de Trenque Lauquen que elabore alcohol en gel - Infoecos","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/#primaryimage"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-03-17T19:30:05+00:00","dateModified":"2020-03-17T19:30:13+00:00","breadcrumb":{"@id":"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/infoecos.com.ar\/index.php\/coronavirus-el-bloque-de-concejales-del-frente-de-todos-le-pide-al-departamento-ejecutivo-de-trenque-lauquen-que-elabore-alcohol-en-gel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoecos.com.ar\/"},{"@type":"ListItem","position":2,"name":"Coronavirus: el bloque de concejales del Frente de Todos le pide al Departamento Ejecutivo de Trenque Lauquen que elabore alcohol en gel"}]},{"@type":"WebSite","@id":"https:\/\/infoecos.com.ar\/#website","url":"https:\/\/infoecos.com.ar\/","name":"Infoecos","description":"Noticias de trenque lauquen y la zona","publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"alternateName":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoecos.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoecos.com.ar\/#organization","name":"Infoecos","alternateName":"Noticias","url":"https:\/\/infoecos.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","width":374,"height":90,"caption":"Infoecos"},"image":{"@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063200290284","https:\/\/x.com\/infoecos"]},{"@type":"Person","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191","name":"Jorge Matheus","url":"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/"}]}},"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","covernews-slider-full":"","covernews-slider-center":"","covernews-featured":"","covernews-medium":"","covernews-medium-square":""},"author_info":{"info":["Jorge Matheus"]},"category_info":"<a href=\"https:\/\/infoecos.com.ar\/index.php\/category\/noticia-secundaria\/\" rel=\"category tag\">Noticia Secundaria<\/a>","tag_info":"Noticia Secundaria","comment_count":"0","_links":{"self":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/59167"}],"collection":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=59167"}],"version-history":[{"count":1,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/59167\/revisions"}],"predecessor-version":[{"id":59168,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/59167\/revisions\/59168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=59167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=59167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=59167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}