{"id":65770,"date":"2020-08-09T22:04:21","date_gmt":"2020-08-10T01:04:21","guid":{"rendered":"http:\/\/infoecos.com.ar\/?p=65770"},"modified":"2020-08-09T22:04:27","modified_gmt":"2020-08-10T01:04:27","slug":"el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus","status":"publish","type":"post","link":"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/","title":{"rendered":"El intendente de Rivadavia confirm\u00f3 este domingo que el distrito contin\u00faa libre de coronavirus"},"content":{"rendered":"\n<p>El Intendente Municipal de Rivadavia, Javier Reynoso, inform\u00f3 este domingo a la comunidad que los hisopados realizados en la semana resultaron negativos. No obstante, los vecinos testeados seguir\u00e1n en cuarentena hasta cumplir con los 14 d\u00edas de aislamiento. Queda exceptuado de esta medida el personal de Salud que, por ser considerado esencial, continuar\u00e1 con sus tareas habituales.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"460\" height=\"240\" src=\"http:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos-460x240.jpg\" alt=\"\" class=\"wp-image-65771\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos-460x240.jpg 460w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos-768x400.jpg 768w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg 787w\" sizes=\"(max-width: 460px) 100vw, 460px\" \/><\/figure><\/div>\n\n\n\n<p>Adem\u00e1s, el Jefe Comunal se refiri\u00f3 al caso positivo de&nbsp;COVID-19 que figura en el sitio web del Ministerio de Salud de la Provincia de Buenos aires, explicando la procedencia de ese dato.<\/p>\n\n\n\n<p>Al respecto de la difusi\u00f3n de informaci\u00f3n no oficial, el Jefe Comunal reflexion\u00f3 sobre la responsabilidad de cada uno de los rivadavienses: \u00abDifundir informaci\u00f3n no oficial afecta a las familias, y a todos aquellos que en ese momento se encuentran esperando un resultado respecto a su salud\u00bb.<\/p>\n\n\n\n<p>Luego, agreg\u00f3: \u00abSer distintos como comunidad ante esta pandemia no es no tener casos, sino contar con la empat\u00eda necesaria para entender que no hay responsables ante una enfermedad que afecta al mundo entero. Nadie gana con una primicia ni festejando un caso positivo. Vamos a ser distintos si aprendemos que todos perdimos mucho ante esta situaci\u00f3n, y que como comunidad debemos apoyarnos y cuidarnos\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-embed-facebook wp-block-embed is-type-video is-provider-facebook\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.facebook.com\/Municipalidad.Rivadavia\/videos\/237111387368696\/\n<\/div><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Intendente Municipal de Rivadavia, Javier Reynoso, inform\u00f3 este domingo a la comunidad que los&#8230;<\/p>\n","protected":false},"author":2,"featured_media":65771,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1613],"tags":[62],"class_list":["post-65770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia-secundaria","tag-rivadavia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El intendente de Rivadavia confirm\u00f3 este domingo que el distrito contin\u00faa libre de coronavirus - Infoecos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El intendente de Rivadavia confirm\u00f3 este domingo que el distrito contin\u00faa libre de coronavirus - Infoecos\" \/>\n<meta property=\"og:description\" content=\"El Intendente Municipal de Rivadavia, Javier Reynoso, inform\u00f3 este domingo a la comunidad que los...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"Infoecos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-10T01:04:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-10T01:04:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"787\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Matheus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infoecos\" \/>\n<meta name=\"twitter:site\" content=\"@infoecos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Matheus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/\"},\"author\":{\"name\":\"Jorge Matheus\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\"},\"headline\":\"El intendente de Rivadavia confirm\u00f3 este domingo que el distrito contin\u00faa libre de coronavirus\",\"datePublished\":\"2020-08-10T01:04:21+00:00\",\"dateModified\":\"2020-08-10T01:04:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/\"},\"wordCount\":232,\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg\",\"keywords\":[\"RIVADAVIA\"],\"articleSection\":[\"Noticia Secundaria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/\",\"name\":\"El intendente de Rivadavia confirm\u00f3 este domingo que el distrito contin\u00faa libre de coronavirus - Infoecos\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg\",\"datePublished\":\"2020-08-10T01:04:21+00:00\",\"dateModified\":\"2020-08-10T01:04:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/#primaryimage\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg\",\"width\":787,\"height\":410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/infoecos.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El intendente de Rivadavia confirm\u00f3 este domingo que el distrito contin\u00faa libre de coronavirus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/infoecos.com.ar\/#website\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"name\":\"Infoecos\",\"description\":\"Noticias de trenque lauquen y la zona\",\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"alternateName\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/infoecos.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/infoecos.com.ar\/#organization\",\"name\":\"Infoecos\",\"alternateName\":\"Noticias\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"width\":374,\"height\":90,\"caption\":\"Infoecos\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\",\"https:\/\/x.com\/infoecos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\",\"name\":\"Jorge Matheus\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El intendente de Rivadavia confirm\u00f3 este domingo que el distrito contin\u00faa libre de coronavirus - Infoecos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/","og_locale":"es_ES","og_type":"article","og_title":"El intendente de Rivadavia confirm\u00f3 este domingo que el distrito contin\u00faa libre de coronavirus - Infoecos","og_description":"El Intendente Municipal de Rivadavia, Javier Reynoso, inform\u00f3 este domingo a la comunidad que los...","og_url":"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/","og_site_name":"Infoecos","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063200290284","article_published_time":"2020-08-10T01:04:21+00:00","article_modified_time":"2020-08-10T01:04:27+00:00","og_image":[{"width":787,"height":410,"url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg","type":"image\/jpeg"}],"author":"Jorge Matheus","twitter_card":"summary_large_image","twitter_creator":"@infoecos","twitter_site":"@infoecos","twitter_misc":{"Escrito por":"Jorge Matheus","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/#article","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/"},"author":{"name":"Jorge Matheus","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191"},"headline":"El intendente de Rivadavia confirm\u00f3 este domingo que el distrito contin\u00faa libre de coronavirus","datePublished":"2020-08-10T01:04:21+00:00","dateModified":"2020-08-10T01:04:27+00:00","mainEntityOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/"},"wordCount":232,"publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg","keywords":["RIVADAVIA"],"articleSection":["Noticia Secundaria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/","url":"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/","name":"El intendente de Rivadavia confirm\u00f3 este domingo que el distrito contin\u00faa libre de coronavirus - Infoecos","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/#primaryimage"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg","datePublished":"2020-08-10T01:04:21+00:00","dateModified":"2020-08-10T01:04:27+00:00","breadcrumb":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/#primaryimage","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg","width":787,"height":410},{"@type":"BreadcrumbList","@id":"https:\/\/infoecos.com.ar\/index.php\/el-intendente-de-rivadavia-confirmo-este-domingo-que-el-distrito-continua-libre-de-coronavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoecos.com.ar\/"},{"@type":"ListItem","position":2,"name":"El intendente de Rivadavia confirm\u00f3 este domingo que el distrito contin\u00faa libre de coronavirus"}]},{"@type":"WebSite","@id":"https:\/\/infoecos.com.ar\/#website","url":"https:\/\/infoecos.com.ar\/","name":"Infoecos","description":"Noticias de trenque lauquen y la zona","publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"alternateName":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoecos.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoecos.com.ar\/#organization","name":"Infoecos","alternateName":"Noticias","url":"https:\/\/infoecos.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","width":374,"height":90,"caption":"Infoecos"},"image":{"@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063200290284","https:\/\/x.com\/infoecos"]},{"@type":"Person","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191","name":"Jorge Matheus","url":"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/"}]}},"featured_image_urls":{"full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg",787,410,false],"thumbnail":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos-150x150.jpg",150,150,true],"medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos-460x240.jpg",460,240,true],"medium_large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos-768x400.jpg",640,333,true],"large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg",640,333,false],"1536x1536":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg",787,410,false],"2048x2048":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg",787,410,false],"covernews-slider-full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg",787,410,false],"covernews-slider-center":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg",787,410,false],"covernews-featured":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos.jpg",787,410,false],"covernews-medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos-720x380.jpg",540,285,true],"covernews-medium-square":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/reynoso_hisopados_negativos-675x410.jpg",400,243,true]},"author_info":{"info":["Jorge Matheus"]},"category_info":"<a href=\"https:\/\/infoecos.com.ar\/index.php\/category\/noticia-secundaria\/\" rel=\"category tag\">Noticia Secundaria<\/a>","tag_info":"Noticia Secundaria","comment_count":"0","_links":{"self":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/65770"}],"collection":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=65770"}],"version-history":[{"count":1,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/65770\/revisions"}],"predecessor-version":[{"id":65772,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/65770\/revisions\/65772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media\/65771"}],"wp:attachment":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=65770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=65770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=65770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}