{"id":76116,"date":"2021-03-17T02:21:25","date_gmt":"2021-03-17T05:21:25","guid":{"rendered":"http:\/\/infoecos.com.ar\/?p=76116"},"modified":"2021-03-22T03:58:17","modified_gmt":"2021-03-22T06:58:17","slug":"se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen","status":"publish","type":"post","link":"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/","title":{"rendered":"Se habilit\u00f3 la pesca comercial para 48 pescadores del distrito de Trenque Lauquen"},"content":{"rendered":"\n<p>El ministerio de Desarrollo Agrario de la Provincia de Buenos Aires habilit\u00f3 desde&nbsp;el lunes la pesca comercial de pejerrey en el complejo lacunar Las Tunas del distrito de Trenque Lauquen y otorg\u00f3 el correspondiente permiso a los 48 pescadores que hab\u00edan gestionado la solicitud a trav\u00e9s del Municipio.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"460\" height=\"270\" src=\"http:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA-460x270.jpg\" alt=\"\" class=\"wp-image-76117\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA-460x270.jpg 460w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg 768w\" sizes=\"(max-width: 460px) 100vw, 460px\" \/><\/figure><\/div>\n\n\n\n<p>\u00abEl domingo a \u00faltima hora recibimos por parte de la Provincia la Resoluci\u00f3n que habilita a los pescadores del distrito de Trenque Lauquen a realizar la actividad comercial en Las Tunas, por lo que desde el lunes temprano cada uno de los habilitados fue abonando los permisos para las credenciales y a partir de ese momento poco a poco est\u00e1n ingresando en conjunto con los inspectores de pesca\u00bb, se\u00f1al\u00f3 la subsecretaria de Desarrollo Econ\u00f3mico y Productivo, Clarisa Fabris.<\/p>\n\n\n\n<p>La funcionaria municipal coment\u00f3 que la lluvia del martes \u00abentorpeci\u00f3 un poco el funcionamiento\u00bb aunque explic\u00f3 que igual \u00abest\u00e1n acomod\u00e1ndose en la laguna para comenzar esta temporada habilitada hasta el 31 de agosto, seg\u00fan dice la Resoluci\u00f3n\u00bb<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"460\" height=\"259\" src=\"http:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/01\/Inscripcion-pesca-de-pejerrey-460x259.jpeg\" alt=\"\" class=\"wp-image-72932\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/01\/Inscripcion-pesca-de-pejerrey-460x259.jpeg 460w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/01\/Inscripcion-pesca-de-pejerrey-920x518.jpeg 920w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/01\/Inscripcion-pesca-de-pejerrey-768x432.jpeg 768w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/01\/Inscripcion-pesca-de-pejerrey-1024x576.jpeg 1024w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/01\/Inscripcion-pesca-de-pejerrey.jpeg 1040w\" sizes=\"(max-width: 460px) 100vw, 460px\" \/><\/figure><\/div>\n\n\n\n<p>Tras precisar que \u00abtenemos habilitados 48 pescadores del distrito, algunos de Trenque Lauquen ciudad y otros de Beruti, dijo que \u00aben estos dos d\u00edas est\u00e1n llegando de a poco con sus equipos, acomodando tambi\u00e9n los camiones que recibir\u00e1n el pescado y los espacios en donde se va a realizar la elaboraci\u00f3n y el procesamiento, sobre todo porque se acerca Semana Santa, que es la fecha en donde se encuentra mayor mercado disponible para insertar el pescado elaborado, que es, en definitiva, lo que nosotros intentamos potenciar, el mayor desarrollo local. A trav\u00e9s de la planta, agregar valor genera no solo m\u00e1s ingresos sino mas fuentes de trabajo\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"http:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/CLARISA-FABRIS-PESCA.mp3\"><\/audio><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Declaraciones de la subsecretaria de Desarrollo Econ\u00f3mico y Productivo, Clarisa Fabris<\/p>\n","protected":false},"author":2,"featured_media":76117,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1327,1334],"tags":[2563],"class_list":["post-76116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-audio","category-inferior14","tag-desde-el-lunes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se habilit\u00f3 la pesca comercial para 48 pescadores del distrito de Trenque Lauquen - Infoecos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se habilit\u00f3 la pesca comercial para 48 pescadores del distrito de Trenque Lauquen - Infoecos\" \/>\n<meta property=\"og:description\" content=\"Declaraciones de la subsecretaria de Desarrollo Econ\u00f3mico y Productivo, Clarisa Fabris\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/\" \/>\n<meta property=\"og:site_name\" content=\"Infoecos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-17T05:21:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-22T06:58:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"451\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Matheus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infoecos\" \/>\n<meta name=\"twitter:site\" content=\"@infoecos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Matheus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/\"},\"author\":{\"name\":\"Jorge Matheus\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\"},\"headline\":\"Se habilit\u00f3 la pesca comercial para 48 pescadores del distrito de Trenque Lauquen\",\"datePublished\":\"2021-03-17T05:21:25+00:00\",\"dateModified\":\"2021-03-22T06:58:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/\"},\"wordCount\":298,\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg\",\"keywords\":[\"DESDE EL LUNES\"],\"articleSection\":[\"Audio\",\"Bloque inferior - 14\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/\",\"name\":\"Se habilit\u00f3 la pesca comercial para 48 pescadores del distrito de Trenque Lauquen - Infoecos\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg\",\"datePublished\":\"2021-03-17T05:21:25+00:00\",\"dateModified\":\"2021-03-22T06:58:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/#primaryimage\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg\",\"width\":768,\"height\":451},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/infoecos.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se habilit\u00f3 la pesca comercial para 48 pescadores del distrito de Trenque Lauquen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/infoecos.com.ar\/#website\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"name\":\"Infoecos\",\"description\":\"Noticias de trenque lauquen y la zona\",\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"alternateName\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/infoecos.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/infoecos.com.ar\/#organization\",\"name\":\"Infoecos\",\"alternateName\":\"Noticias\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"width\":374,\"height\":90,\"caption\":\"Infoecos\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\",\"https:\/\/x.com\/infoecos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\",\"name\":\"Jorge Matheus\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se habilit\u00f3 la pesca comercial para 48 pescadores del distrito de Trenque Lauquen - Infoecos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/","og_locale":"es_ES","og_type":"article","og_title":"Se habilit\u00f3 la pesca comercial para 48 pescadores del distrito de Trenque Lauquen - Infoecos","og_description":"Declaraciones de la subsecretaria de Desarrollo Econ\u00f3mico y Productivo, Clarisa Fabris","og_url":"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/","og_site_name":"Infoecos","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063200290284","article_published_time":"2021-03-17T05:21:25+00:00","article_modified_time":"2021-03-22T06:58:17+00:00","og_image":[{"width":768,"height":451,"url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg","type":"image\/jpeg"}],"author":"Jorge Matheus","twitter_card":"summary_large_image","twitter_creator":"@infoecos","twitter_site":"@infoecos","twitter_misc":{"Escrito por":"Jorge Matheus","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/#article","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/"},"author":{"name":"Jorge Matheus","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191"},"headline":"Se habilit\u00f3 la pesca comercial para 48 pescadores del distrito de Trenque Lauquen","datePublished":"2021-03-17T05:21:25+00:00","dateModified":"2021-03-22T06:58:17+00:00","mainEntityOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/"},"wordCount":298,"publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg","keywords":["DESDE EL LUNES"],"articleSection":["Audio","Bloque inferior - 14"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/","url":"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/","name":"Se habilit\u00f3 la pesca comercial para 48 pescadores del distrito de Trenque Lauquen - Infoecos","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/#primaryimage"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg","datePublished":"2021-03-17T05:21:25+00:00","dateModified":"2021-03-22T06:58:17+00:00","breadcrumb":{"@id":"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/#primaryimage","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg","width":768,"height":451},{"@type":"BreadcrumbList","@id":"https:\/\/infoecos.com.ar\/index.php\/se-habilito-la-pesca-comercial-para-48-pescadores-del-distrito-de-trenque-lauquen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoecos.com.ar\/"},{"@type":"ListItem","position":2,"name":"Se habilit\u00f3 la pesca comercial para 48 pescadores del distrito de Trenque Lauquen"}]},{"@type":"WebSite","@id":"https:\/\/infoecos.com.ar\/#website","url":"https:\/\/infoecos.com.ar\/","name":"Infoecos","description":"Noticias de trenque lauquen y la zona","publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"alternateName":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoecos.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoecos.com.ar\/#organization","name":"Infoecos","alternateName":"Noticias","url":"https:\/\/infoecos.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","width":374,"height":90,"caption":"Infoecos"},"image":{"@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063200290284","https:\/\/x.com\/infoecos"]},{"@type":"Person","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191","name":"Jorge Matheus","url":"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/"}]}},"featured_image_urls":{"full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg",768,451,false],"thumbnail":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA-150x150.jpg",150,150,true],"medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA-460x270.jpg",460,270,true],"medium_large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg",640,376,false],"large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg",640,376,false],"1536x1536":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg",768,451,false],"2048x2048":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg",768,451,false],"covernews-slider-full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg",768,451,false],"covernews-slider-center":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg",768,451,false],"covernews-featured":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA.jpg",768,451,false],"covernews-medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA-720x380.jpg",540,285,true],"covernews-medium-square":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/03\/PESCA-675x450.jpg",375,250,true]},"author_info":{"info":["Jorge Matheus"]},"category_info":"<a href=\"https:\/\/infoecos.com.ar\/index.php\/category\/audio\/\" rel=\"category tag\">Audio<\/a> <a href=\"https:\/\/infoecos.com.ar\/index.php\/category\/inferior14\/\" rel=\"category tag\">Bloque inferior - 14<\/a>","tag_info":"Bloque inferior - 14","comment_count":"0","_links":{"self":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/76116"}],"collection":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=76116"}],"version-history":[{"count":2,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/76116\/revisions"}],"predecessor-version":[{"id":76206,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/76116\/revisions\/76206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media\/76117"}],"wp:attachment":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=76116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=76116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=76116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}