{"id":76987,"date":"2021-03-29T01:38:59","date_gmt":"2021-03-29T04:38:59","guid":{"rendered":"http:\/\/infoecos.com.ar\/?p=76987"},"modified":"2021-03-30T02:18:43","modified_gmt":"2021-03-30T05:18:43","slug":"provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno","status":"publish","type":"post","link":"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/","title":{"rendered":"Provincia de Buenos Aires reasigna fecha a quienes no asisten a vacunarse sin rechazar el turno"},"content":{"rendered":"\n<p><strong>La provincia de Buenos Aires aclar\u00f3 que cuando alguien se ausenta del turno asignado para su vacunaci\u00f3n, sin rechazarlo, es reincorporado al grupo de personas sin turno, a la espera de una nueva asignaci\u00f3n de d\u00eda y horario.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"460\" src=\"http:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-306x460.jpg\" alt=\"\" class=\"wp-image-74637\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-306x460.jpg 306w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-612x920.jpg 612w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-768x1154.jpg 768w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-1022x1536.jpg 1022w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-1363x2048.jpg 1363w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-1024x1539.jpg 1024w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-scaled.jpg 1703w\" sizes=\"(max-width: 306px) 100vw, 306px\" \/><\/figure><\/div>\n\n\n\n<p>\u00abLa aplicaci\u00f3n Vacunate PBA, en algunos casos, cuando una persona NO ASISTE al turno asignado por el motivo que fuera y NO RECHAZA dicho turno, la registra como ATENDIDO, de forma autom\u00e1tica\u00bb, sostuvo un posteo en la cuanta oficial del Ministerio de Salud provincial en la red social Twitter.<\/p>\n\n\n\n<p>\u00abLuego, cuando a fin de jornada se actualizan los datos con el sistema \u00fanico de carga de vacunas, el estado se corrige, y se lo registra como AUSENTE. Se procede entonces a reincorporarlo al grupo de las personas sin turno, a la espera de una nueva asignaci\u00f3n de d\u00eda y horario\u00bb, agrega.<\/p>\n\n\n\n<p>\u00abClaramente, no se trata de ninguna irregularidad y no representa ning\u00fan perjuicio ni ventaja para nadie. La situaci\u00f3n es originada porque la persona se ausenta y la aplicaci\u00f3n todav\u00eda no lo registra y la considera atendida. Despu\u00e9s, en pocas horas el sistema se actualiza\u00bb, abund\u00f3.<\/p>\n\n\n\n<p>Seg\u00fan el Ministerio de Salud bonaerense, \u00abel beneficio de contar con un sistema p\u00fablico y \u00fanico nos permite detectar y auditar cada caso, lo cual ser\u00eda imposible con un sistema privatizado\u00bb. \u00abRecordamos que, para situaciones que generen dudas, est\u00e1 habilitado el bot\u00f3n de denuncias en la Web y en la APP\u00bb, precis\u00f3.<\/p>\n\n\n\n<p>\u00abApelamos a la responsabilidad para no generar confusi\u00f3n con denuncias infundadas, que atentan contra la expectativa y la esperanza de millones de bonaerenses, que est\u00e1n recibiendo su vacuna en los 135 municipios de la Provincia de Buenos Aires\u00bb, concluye.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan el Ministerio de Salud bonaerense, \u00abel beneficio de contar con un sistema p\u00fablico y \u00fanico nos permite detectar y auditar cada caso\u00bb  y que no se trata de ninguna irregularidad y no representa ning\u00fan perjuicio ni ventaja para nadie<\/p>\n","protected":false},"author":2,"featured_media":74637,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1614],"tags":[3467],"class_list":["post-76987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c2nota7","tag-aclaracion-del-ministerio-de-salud"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Provincia de Buenos Aires reasigna fecha a quienes no asisten a vacunarse sin rechazar el turno - Infoecos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Provincia de Buenos Aires reasigna fecha a quienes no asisten a vacunarse sin rechazar el turno - Infoecos\" \/>\n<meta property=\"og:description\" content=\"Seg\u00fan el Ministerio de Salud bonaerense, &quot;el beneficio de contar con un sistema p\u00fablico y \u00fanico nos permite detectar y auditar cada caso&quot; y que no se trata de ninguna irregularidad y no representa ning\u00fan perjuicio ni ventaja para nadie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/\" \/>\n<meta property=\"og:site_name\" content=\"Infoecos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-29T04:38:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-30T05:18:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1703\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Matheus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infoecos\" \/>\n<meta name=\"twitter:site\" content=\"@infoecos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Matheus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/\"},\"author\":{\"name\":\"Jorge Matheus\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\"},\"headline\":\"Provincia de Buenos Aires reasigna fecha a quienes no asisten a vacunarse sin rechazar el turno\",\"datePublished\":\"2021-03-29T04:38:59+00:00\",\"dateModified\":\"2021-03-30T05:18:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/\"},\"wordCount\":308,\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-scaled.jpg\",\"keywords\":[\"ACLARACI\u00d3N DEL MINISTERIO DE SALUD\"],\"articleSection\":[\"C2 N7\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/\",\"name\":\"Provincia de Buenos Aires reasigna fecha a quienes no asisten a vacunarse sin rechazar el turno - Infoecos\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-scaled.jpg\",\"datePublished\":\"2021-03-29T04:38:59+00:00\",\"dateModified\":\"2021-03-30T05:18:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/#primaryimage\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-scaled.jpg\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-scaled.jpg\",\"width\":1703,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/infoecos.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Provincia de Buenos Aires reasigna fecha a quienes no asisten a vacunarse sin rechazar el turno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/infoecos.com.ar\/#website\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"name\":\"Infoecos\",\"description\":\"Noticias de trenque lauquen y la zona\",\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"alternateName\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/infoecos.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/infoecos.com.ar\/#organization\",\"name\":\"Infoecos\",\"alternateName\":\"Noticias\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"width\":374,\"height\":90,\"caption\":\"Infoecos\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\",\"https:\/\/x.com\/infoecos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\",\"name\":\"Jorge Matheus\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Provincia de Buenos Aires reasigna fecha a quienes no asisten a vacunarse sin rechazar el turno - Infoecos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/","og_locale":"es_ES","og_type":"article","og_title":"Provincia de Buenos Aires reasigna fecha a quienes no asisten a vacunarse sin rechazar el turno - Infoecos","og_description":"Seg\u00fan el Ministerio de Salud bonaerense, \"el beneficio de contar con un sistema p\u00fablico y \u00fanico nos permite detectar y auditar cada caso\" y que no se trata de ninguna irregularidad y no representa ning\u00fan perjuicio ni ventaja para nadie","og_url":"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/","og_site_name":"Infoecos","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063200290284","article_published_time":"2021-03-29T04:38:59+00:00","article_modified_time":"2021-03-30T05:18:43+00:00","og_image":[{"width":1703,"height":2560,"url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-scaled.jpg","type":"image\/jpeg"}],"author":"Jorge Matheus","twitter_card":"summary_large_image","twitter_creator":"@infoecos","twitter_site":"@infoecos","twitter_misc":{"Escrito por":"Jorge Matheus","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/#article","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/"},"author":{"name":"Jorge Matheus","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191"},"headline":"Provincia de Buenos Aires reasigna fecha a quienes no asisten a vacunarse sin rechazar el turno","datePublished":"2021-03-29T04:38:59+00:00","dateModified":"2021-03-30T05:18:43+00:00","mainEntityOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/"},"wordCount":308,"publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-scaled.jpg","keywords":["ACLARACI\u00d3N DEL MINISTERIO DE SALUD"],"articleSection":["C2 N7"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/","url":"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/","name":"Provincia de Buenos Aires reasigna fecha a quienes no asisten a vacunarse sin rechazar el turno - Infoecos","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/#primaryimage"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-scaled.jpg","datePublished":"2021-03-29T04:38:59+00:00","dateModified":"2021-03-30T05:18:43+00:00","breadcrumb":{"@id":"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/#primaryimage","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-scaled.jpg","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-scaled.jpg","width":1703,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/infoecos.com.ar\/index.php\/provincia-de-buenos-aires-reasigna-fecha-a-quienes-no-asisten-a-vacunarse-sin-rechazar-el-turno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoecos.com.ar\/"},{"@type":"ListItem","position":2,"name":"Provincia de Buenos Aires reasigna fecha a quienes no asisten a vacunarse sin rechazar el turno"}]},{"@type":"WebSite","@id":"https:\/\/infoecos.com.ar\/#website","url":"https:\/\/infoecos.com.ar\/","name":"Infoecos","description":"Noticias de trenque lauquen y la zona","publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"alternateName":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoecos.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoecos.com.ar\/#organization","name":"Infoecos","alternateName":"Noticias","url":"https:\/\/infoecos.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","width":374,"height":90,"caption":"Infoecos"},"image":{"@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063200290284","https:\/\/x.com\/infoecos"]},{"@type":"Person","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191","name":"Jorge Matheus","url":"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/"}]}},"featured_image_urls":{"full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-scaled.jpg",1703,2560,false],"thumbnail":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-150x150.jpg",150,150,true],"medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-306x460.jpg",306,460,true],"medium_large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-768x1154.jpg",640,962,true],"large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-612x920.jpg",612,920,true],"1536x1536":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-1022x1536.jpg",1022,1536,true],"2048x2048":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-1363x2048.jpg",1363,2048,true],"covernews-slider-full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-1536x1020.jpg",1077,715,true],"covernews-slider-center":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-936x897.jpg",522,500,true],"covernews-featured":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-1024x1539.jpg",1024,1539,true],"covernews-medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-720x380.jpg",540,285,true],"covernews-medium-square":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/02\/210220-Vacuna-Ensenada_1100-675x450.jpg",375,250,true]},"author_info":{"info":["Jorge Matheus"]},"category_info":"<a href=\"https:\/\/infoecos.com.ar\/index.php\/category\/c2nota7\/\" rel=\"category tag\">C2 N7<\/a>","tag_info":"C2 N7","comment_count":"0","_links":{"self":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/76987"}],"collection":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=76987"}],"version-history":[{"count":1,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/76987\/revisions"}],"predecessor-version":[{"id":76988,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/76987\/revisions\/76988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media\/74637"}],"wp:attachment":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=76987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=76987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=76987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}