{"id":77601,"date":"2021-05-04T00:42:04","date_gmt":"2021-05-04T03:42:04","guid":{"rendered":"http:\/\/infoecos.com.ar\/?p=77601"},"modified":"2021-05-07T00:38:12","modified_gmt":"2021-05-07T03:38:12","slug":"10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios","status":"publish","type":"post","link":"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/","title":{"rendered":"10 mil millones de pesos en cr\u00e9ditos para peque\u00f1os productores agropecuarios"},"content":{"rendered":"\n<p>El Banco de la Naci\u00f3n Argentina (BNA) destinar\u00e1 $ 10.000 millones para financiar a micro, peque\u00f1os y medianos productores de trigo, cebada y legumbres para solventar sus gastos de siembra y conexos de granos en el lanzamiento de la campa\u00f1a fina 2021\/22.<\/p>\n\n\n\n<p>La l\u00ednea alcanza a<strong>&nbsp;mipymes de hasta 200 hect\u00e1reas de todo el pa\u00eds y contempla la compra de insumos, semillas, fertilizantes, combustibles y gastos conexos.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"http:\/\/infoecos.com.ar\/wp-content\/uploads\/54617aa257455.jpg\" alt=\"\" class=\"wp-image-15634\"\/><figcaption>Banco Naci\u00f3n &#8211; Casa Central<\/figcaption><\/figure><\/div>\n\n\n\n<p><strong>\u201cEsta iniciativa apunta al aumento de la producci\u00f3n de manera sustentable y elevando los est\u00e1ndares de calidad de los granos, as\u00ed como al incremento en el abastecimiento interno\u201d, expres\u00f3 el presidente del BNA, Eduardo Hecker.<\/strong><\/p>\n\n\n\n<p>\u201c<strong>Buscamos lograr mayores niveles de exportaci\u00f3n para incrementar el ingreso de divisas al pa\u00eds y abrir puertas a nuevos mercados para nuestra producci\u00f3n\u201d<\/strong>, agreg\u00f3 el titular del BNA en un comunicado.<\/p>\n\n\n\n<p>Los pr\u00e9stamos ser\u00e1n en pesos, con una tasa de inter\u00e9s fija del 29% nominal anual y una proporci\u00f3n de apoyo alcanzar\u00e1 hasta el 80% de los gastos corrientes de la zona.<\/p>\n\n\n\n<p>El plazo de devoluci\u00f3n del cr\u00e9dito ser\u00e1 de hasta 180 d\u00edas, con la posibilidad de ser prorrogado hasta 90 d\u00edas adicionales, de modo que el plazo de repago calce con la \u00e9poca habitual de comercializaci\u00f3n del producto en la zona, sin exceder el 2 de marzo de 2022.<\/p>\n\n\n\n<p>Entre otros aspectos t\u00e9cnicos, el BNA explic\u00f3 que el esquema de amortizaci\u00f3n ser\u00e1 a trav\u00e9s del sistema alem\u00e1n, con un pago de capital integro al vencimiento de la operaci\u00f3n y los servicios de inter\u00e9s pagaderos como m\u00e1ximo semestralmente, sin per\u00edodo de gracia.<\/p>\n\n\n\n<p><strong>Si bien el cupo del cr\u00e9dito es de $ 10.000 millones, desembolsable en dos tramos de $ 5.000 millones, el Banco sostuvo que podr\u00e1 ser ampliado<\/strong>&nbsp;conforme a cual sea la capacidad prestable de la entidad en los pr\u00f3ximos meses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEsta iniciativa apunta al aumento de la producci\u00f3n de manera sustentable y elevando los est\u00e1ndares de calidad de los granos, as\u00ed como al incremento en el abastecimiento interno\u201d, expres\u00f3 el presidente del BNA, Eduardo Hecker<\/p>\n","protected":false},"author":2,"featured_media":15634,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1330],"tags":[97],"class_list":["post-77601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inferior10","tag-economia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>10 mil millones de pesos en cr\u00e9ditos para peque\u00f1os productores agropecuarios - Infoecos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 mil millones de pesos en cr\u00e9ditos para peque\u00f1os productores agropecuarios - Infoecos\" \/>\n<meta property=\"og:description\" content=\"\u201cEsta iniciativa apunta al aumento de la producci\u00f3n de manera sustentable y elevando los est\u00e1ndares de calidad de los granos, as\u00ed como al incremento en el abastecimiento interno\u201d, expres\u00f3 el presidente del BNA, Eduardo Hecker\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/\" \/>\n<meta property=\"og:site_name\" content=\"Infoecos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-04T03:42:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-07T03:38:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/54617aa257455.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"412\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Matheus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infoecos\" \/>\n<meta name=\"twitter:site\" content=\"@infoecos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Matheus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/\"},\"author\":{\"name\":\"Jorge Matheus\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\"},\"headline\":\"10 mil millones de pesos en cr\u00e9ditos para peque\u00f1os productores agropecuarios\",\"datePublished\":\"2021-05-04T03:42:04+00:00\",\"dateModified\":\"2021-05-07T03:38:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/\"},\"wordCount\":330,\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"ECONOM\u00cdA\"],\"articleSection\":[\"Bloque inferior - 10\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/\",\"name\":\"10 mil millones de pesos en cr\u00e9ditos para peque\u00f1os productores agropecuarios - Infoecos\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-05-04T03:42:04+00:00\",\"dateModified\":\"2021-05-07T03:38:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/infoecos.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 mil millones de pesos en cr\u00e9ditos para peque\u00f1os productores agropecuarios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/infoecos.com.ar\/#website\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"name\":\"Infoecos\",\"description\":\"Noticias de trenque lauquen y la zona\",\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"alternateName\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/infoecos.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/infoecos.com.ar\/#organization\",\"name\":\"Infoecos\",\"alternateName\":\"Noticias\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"width\":374,\"height\":90,\"caption\":\"Infoecos\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\",\"https:\/\/x.com\/infoecos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\",\"name\":\"Jorge Matheus\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 mil millones de pesos en cr\u00e9ditos para peque\u00f1os productores agropecuarios - Infoecos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/","og_locale":"es_ES","og_type":"article","og_title":"10 mil millones de pesos en cr\u00e9ditos para peque\u00f1os productores agropecuarios - Infoecos","og_description":"\u201cEsta iniciativa apunta al aumento de la producci\u00f3n de manera sustentable y elevando los est\u00e1ndares de calidad de los granos, as\u00ed como al incremento en el abastecimiento interno\u201d, expres\u00f3 el presidente del BNA, Eduardo Hecker","og_url":"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/","og_site_name":"Infoecos","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063200290284","article_published_time":"2021-05-04T03:42:04+00:00","article_modified_time":"2021-05-07T03:38:12+00:00","og_image":[{"width":550,"height":412,"url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/54617aa257455.jpg","type":"image\/jpeg"}],"author":"Jorge Matheus","twitter_card":"summary_large_image","twitter_creator":"@infoecos","twitter_site":"@infoecos","twitter_misc":{"Escrito por":"Jorge Matheus","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/#article","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/"},"author":{"name":"Jorge Matheus","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191"},"headline":"10 mil millones de pesos en cr\u00e9ditos para peque\u00f1os productores agropecuarios","datePublished":"2021-05-04T03:42:04+00:00","dateModified":"2021-05-07T03:38:12+00:00","mainEntityOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/"},"wordCount":330,"publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/#primaryimage"},"thumbnailUrl":"","keywords":["ECONOM\u00cdA"],"articleSection":["Bloque inferior - 10"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/","url":"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/","name":"10 mil millones de pesos en cr\u00e9ditos para peque\u00f1os productores agropecuarios - Infoecos","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/#primaryimage"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-05-04T03:42:04+00:00","dateModified":"2021-05-07T03:38:12+00:00","breadcrumb":{"@id":"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/infoecos.com.ar\/index.php\/10-mil-millones-de-pesos-en-creditos-para-pequenos-productores-agropecuarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoecos.com.ar\/"},{"@type":"ListItem","position":2,"name":"10 mil millones de pesos en cr\u00e9ditos para peque\u00f1os productores agropecuarios"}]},{"@type":"WebSite","@id":"https:\/\/infoecos.com.ar\/#website","url":"https:\/\/infoecos.com.ar\/","name":"Infoecos","description":"Noticias de trenque lauquen y la zona","publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"alternateName":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoecos.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoecos.com.ar\/#organization","name":"Infoecos","alternateName":"Noticias","url":"https:\/\/infoecos.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","width":374,"height":90,"caption":"Infoecos"},"image":{"@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063200290284","https:\/\/x.com\/infoecos"]},{"@type":"Person","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191","name":"Jorge Matheus","url":"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/"}]}},"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","covernews-slider-full":"","covernews-slider-center":"","covernews-featured":"","covernews-medium":"","covernews-medium-square":""},"author_info":{"info":["Jorge Matheus"]},"category_info":"<a href=\"https:\/\/infoecos.com.ar\/index.php\/category\/inferior10\/\" rel=\"category tag\">Bloque inferior - 10<\/a>","tag_info":"Bloque inferior - 10","comment_count":"0","_links":{"self":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/77601"}],"collection":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=77601"}],"version-history":[{"count":1,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/77601\/revisions"}],"predecessor-version":[{"id":77602,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/77601\/revisions\/77602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=77601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=77601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=77601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}