{"id":78759,"date":"2021-05-27T01:03:53","date_gmt":"2021-05-27T04:03:53","guid":{"rendered":"http:\/\/infoecos.com.ar\/?p=78759"},"modified":"2021-05-27T23:58:16","modified_gmt":"2021-05-28T02:58:16","slug":"el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales","status":"publish","type":"post","link":"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/","title":{"rendered":"El Gobierno acord\u00f3 un aumento del 35% en seis tramos para los empleados estatales nacionales"},"content":{"rendered":"\n<p>El Gobierno nacional acord\u00f3 un aumento del 35% distribuido en seis tramos para la paritaria 2021-2022 en el marco del convenio colectivo de trabajo para el empleo p\u00fablico nacional, con los sindicatos Uni\u00f3n Personal Civil de la Naci\u00f3n (UPCN) y la Asociaci\u00f3n de Trabajadores del Estado (ATE).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"460\" height=\"259\" src=\"http:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales-460x259.jpg\" alt=\"\" class=\"wp-image-78760\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales-460x259.jpg 460w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales-920x518.jpg 920w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales-768x432.jpg 768w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales.jpg 1004w\" sizes=\"(max-width: 460px) 100vw, 460px\" \/><\/figure><\/div>\n\n\n\n<p>Seg\u00fan se inform\u00f3 oficialmente, la Secretar\u00eda de Gesti\u00f3n y Empleo P\u00fablico de la Jefatura de Gabinete de Ministros acord\u00f3 con ambos gremios, UPCN y ATE, el aumento de un 35 por ciento para el per\u00edodo paritario junio 202-mayo 2022, de los cuales el 24% se dar\u00e1 dentro de este a\u00f1o mientras que el restante 11% se sumar\u00e1 en enero y febrero.<\/p>\n\n\n\n<p>El convenio se rubric\u00f3 con la presencia del Ministro de Trabajo, Claudio Moroni; la secretaria de Gesti\u00f3n y Empleo P\u00fablico, Ana Castellani, y los representantes de ambos sindicatos: Felipe Carrillo por UPCN y Hugo Godoy por ATE.<\/p>\n\n\n\n<p>De acuerdo con lo establecido, los tramos del aumento salarial para la administraci\u00f3n p\u00fablica nacional se distribuir\u00e1n de la siguiente manera: 10% en junio, 5% en agosto, 5% en septiembre, 4% en diciembre, 6% en enero y 5% en febrero.<\/p>\n\n\n\n<p>Adem\u00e1s, se incrementaron los reintegros por guarder\u00eda y se ampli\u00f3 el universo de trabajadoras y trabajadores que pueden cobrarlos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s, se incrementaron los reintegros por guarder\u00eda y se ampli\u00f3 el universo de trabajadoras y trabajadores que pueden cobrarlos<\/p>\n","protected":false},"author":2,"featured_media":78760,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1643],"tags":[3770],"class_list":["post-78759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inferior16","tag-en-porcentuales-hasta-febrero"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Gobierno acord\u00f3 un aumento del 35% en seis tramos para los empleados estatales nacionales - Infoecos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno acord\u00f3 un aumento del 35% en seis tramos para los empleados estatales nacionales - Infoecos\" \/>\n<meta property=\"og:description\" content=\"Adem\u00e1s, se incrementaron los reintegros por guarder\u00eda y se ampli\u00f3 el universo de trabajadoras y trabajadores que pueden cobrarlos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/\" \/>\n<meta property=\"og:site_name\" content=\"Infoecos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-27T04:03:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-28T02:58:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1004\" \/>\n\t<meta property=\"og:image:height\" content=\"565\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Matheus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infoecos\" \/>\n<meta name=\"twitter:site\" content=\"@infoecos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Matheus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/\"},\"author\":{\"name\":\"Jorge Matheus\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\"},\"headline\":\"El Gobierno acord\u00f3 un aumento del 35% en seis tramos para los empleados estatales nacionales\",\"datePublished\":\"2021-05-27T04:03:53+00:00\",\"dateModified\":\"2021-05-28T02:58:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/\"},\"wordCount\":224,\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales.jpg\",\"keywords\":[\"en porcentuales hasta febrero\"],\"articleSection\":[\"Bloque inferior - 16\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/\",\"name\":\"El Gobierno acord\u00f3 un aumento del 35% en seis tramos para los empleados estatales nacionales - Infoecos\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales.jpg\",\"datePublished\":\"2021-05-27T04:03:53+00:00\",\"dateModified\":\"2021-05-28T02:58:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/#primaryimage\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales.jpg\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales.jpg\",\"width\":1004,\"height\":565},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/infoecos.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno acord\u00f3 un aumento del 35% en seis tramos para los empleados estatales nacionales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/infoecos.com.ar\/#website\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"name\":\"Infoecos\",\"description\":\"Noticias de trenque lauquen y la zona\",\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"alternateName\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/infoecos.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/infoecos.com.ar\/#organization\",\"name\":\"Infoecos\",\"alternateName\":\"Noticias\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"width\":374,\"height\":90,\"caption\":\"Infoecos\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\",\"https:\/\/x.com\/infoecos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\",\"name\":\"Jorge Matheus\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno acord\u00f3 un aumento del 35% en seis tramos para los empleados estatales nacionales - Infoecos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno acord\u00f3 un aumento del 35% en seis tramos para los empleados estatales nacionales - Infoecos","og_description":"Adem\u00e1s, se incrementaron los reintegros por guarder\u00eda y se ampli\u00f3 el universo de trabajadoras y trabajadores que pueden cobrarlos","og_url":"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/","og_site_name":"Infoecos","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063200290284","article_published_time":"2021-05-27T04:03:53+00:00","article_modified_time":"2021-05-28T02:58:16+00:00","og_image":[{"width":1004,"height":565,"url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales.jpg","type":"image\/jpeg"}],"author":"Jorge Matheus","twitter_card":"summary_large_image","twitter_creator":"@infoecos","twitter_site":"@infoecos","twitter_misc":{"Escrito por":"Jorge Matheus","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/#article","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/"},"author":{"name":"Jorge Matheus","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191"},"headline":"El Gobierno acord\u00f3 un aumento del 35% en seis tramos para los empleados estatales nacionales","datePublished":"2021-05-27T04:03:53+00:00","dateModified":"2021-05-28T02:58:16+00:00","mainEntityOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/"},"wordCount":224,"publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales.jpg","keywords":["en porcentuales hasta febrero"],"articleSection":["Bloque inferior - 16"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/","url":"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/","name":"El Gobierno acord\u00f3 un aumento del 35% en seis tramos para los empleados estatales nacionales - Infoecos","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/#primaryimage"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales.jpg","datePublished":"2021-05-27T04:03:53+00:00","dateModified":"2021-05-28T02:58:16+00:00","breadcrumb":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/#primaryimage","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales.jpg","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales.jpg","width":1004,"height":565},{"@type":"BreadcrumbList","@id":"https:\/\/infoecos.com.ar\/index.php\/el-gobierno-acordo-un-aumento-del-35-en-seis-tramos-para-los-empleados-estatales-nacionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoecos.com.ar\/"},{"@type":"ListItem","position":2,"name":"El Gobierno acord\u00f3 un aumento del 35% en seis tramos para los empleados estatales nacionales"}]},{"@type":"WebSite","@id":"https:\/\/infoecos.com.ar\/#website","url":"https:\/\/infoecos.com.ar\/","name":"Infoecos","description":"Noticias de trenque lauquen y la zona","publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"alternateName":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoecos.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoecos.com.ar\/#organization","name":"Infoecos","alternateName":"Noticias","url":"https:\/\/infoecos.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","width":374,"height":90,"caption":"Infoecos"},"image":{"@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063200290284","https:\/\/x.com\/infoecos"]},{"@type":"Person","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191","name":"Jorge Matheus","url":"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/"}]}},"featured_image_urls":{"full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales.jpg",1004,565,false],"thumbnail":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales-150x150.jpg",150,150,true],"medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales-460x259.jpg",460,259,true],"medium_large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales-768x432.jpg",640,360,true],"large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales-920x518.jpg",640,360,true],"1536x1536":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales.jpg",1004,565,false],"2048x2048":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales.jpg",1004,565,false],"covernews-slider-full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales.jpg",1004,565,false],"covernews-slider-center":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales-936x565.jpg",800,483,true],"covernews-featured":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales.jpg",1004,565,false],"covernews-medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales-720x380.jpg",540,285,true],"covernews-medium-square":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/acuerdoestatales-675x450.jpg",375,250,true]},"author_info":{"info":["Jorge Matheus"]},"category_info":"<a href=\"https:\/\/infoecos.com.ar\/index.php\/category\/inferior16\/\" rel=\"category tag\">Bloque inferior - 16<\/a>","tag_info":"Bloque inferior - 16","comment_count":"0","_links":{"self":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/78759"}],"collection":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=78759"}],"version-history":[{"count":1,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/78759\/revisions"}],"predecessor-version":[{"id":78761,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/78759\/revisions\/78761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media\/78760"}],"wp:attachment":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=78759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=78759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=78759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}