{"id":79312,"date":"2021-06-09T15:57:34","date_gmt":"2021-06-09T18:57:34","guid":{"rendered":"http:\/\/infoecos.com.ar\/?p=79312"},"modified":"2021-06-09T15:57:34","modified_gmt":"2021-06-09T18:57:34","slug":"sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen","status":"publish","type":"post","link":"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/","title":{"rendered":"Sigue siendo alto el n\u00famero de casos activos en el distrito de Trenque Lauquen"},"content":{"rendered":"\n<p>Cincuenta y nueve (59) nuevos casos confirmados de Covid-19, 47 personas recuperadas m\u00e1s, 95 casos descartados, 71 casos sospechosos y 342 personas en aislamiento en todo el distrito, fueron reportados este mi\u00e9rcoles por la subsecretar\u00eda de Salud municipal de Trenque Lauquen que, con estos datos, inform\u00f3 que los casos activos son 486.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"460\" height=\"434\" src=\"http:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/reportemiercoles-1-460x434.jpg\" alt=\"\" class=\"wp-image-79313\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/reportemiercoles-1-460x434.jpg 460w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/reportemiercoles-1-768x725.jpg 768w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/reportemiercoles-1.jpg 800w\" sizes=\"(max-width: 460px) 100vw, 460px\" \/><\/figure><\/div>\n\n\n\n<p>Cuarenta y uno (41) de los 59 nuevos casos positivos fueron diagnosticados por hisopado y los 18 restantes por criterio o nexo epidemiol\u00f3gico seg\u00fan protocolo actualizado vigente, y 46 corresponden a Trenque Lauquen y 13 a Treinta de Agosto.<\/p>\n\n\n\n<p>De los 486 casos activos, 409 pertenecen a la ciudad cabecera, 53 a Treinta de Agosto y 24 a Beruti: 43 se encuentran internados en el Hospital Municipal, uno (1) est\u00e1 en el Centro Extrahospitalario del ex Hotel Pailla Hu\u00e9 y 442 en sus domicilios particulares.<\/p>\n\n\n\n<p>Entre las 47 personas que se recuperaron en las \u00faltimas 24 horas, 42 son de Trenque Lauquen, cuatro (4) de Treinta de Agosto y uno (1) de Beruti, sumando 6.318 las que recibieron el alta desde marzo del a\u00f1o pasado hasta ahora. Un caso fue reasignado en la fecha.<\/p>\n\n\n\n<p>En el mismo per\u00edodo fueron descartados 11.908 casos, incluidos los 95 de la fecha, 83 de Trenque Lauquen y trece (13) de Treinta de Agosto. La suma del desglose por localidad da un total de 96 casos, pero uno de ellos fue reasignado en el d\u00eda de la fecha.<\/p>\n\n\n\n<p>Hasta este mi\u00e9rcoles se registraban 71casos sospechosos -54 de Trenque Lauquen, 16 de Treinta de Agosto y uno (1) de Beruti- y hay 342 personas en aislamiento -288 de Trenque Lauquen, 35 de Treinta de Agosto y 19 de Beruti-.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De los 486 casos activos, 409 pertenecen a la ciudad cabecera, 53 a Treinta de Agosto y 24 a Beruti: 43 se encuentran internados en el Hospital Municipal, uno (1) est\u00e1 en el Centro Extrahospitalario del ex Hotel Pailla Hu\u00e9 y 442 en sus domicilios particulares<\/p>\n","protected":false},"author":2,"featured_media":48389,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1613],"tags":[1785],"class_list":["post-79312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia-secundaria","tag-coronavirus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sigue siendo alto el n\u00famero de casos activos en el distrito de Trenque Lauquen - Infoecos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sigue siendo alto el n\u00famero de casos activos en el distrito de Trenque Lauquen - Infoecos\" \/>\n<meta property=\"og:description\" content=\"De los 486 casos activos, 409 pertenecen a la ciudad cabecera, 53 a Treinta de Agosto y 24 a Beruti: 43 se encuentran internados en el Hospital Municipal, uno (1) est\u00e1 en el Centro Extrahospitalario del ex Hotel Pailla Hu\u00e9 y 442 en sus domicilios particulares\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/\" \/>\n<meta property=\"og:site_name\" content=\"Infoecos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-09T18:57:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/Acceso-23062017-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Matheus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infoecos\" \/>\n<meta name=\"twitter:site\" content=\"@infoecos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Matheus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/\"},\"author\":{\"name\":\"Jorge Matheus\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\"},\"headline\":\"Sigue siendo alto el n\u00famero de casos activos en el distrito de Trenque Lauquen\",\"datePublished\":\"2021-06-09T18:57:34+00:00\",\"dateModified\":\"2021-06-09T18:57:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/\"},\"wordCount\":265,\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"CORONAVIRUS\"],\"articleSection\":[\"Noticia Secundaria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/\",\"name\":\"Sigue siendo alto el n\u00famero de casos activos en el distrito de Trenque Lauquen - Infoecos\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-06-09T18:57:34+00:00\",\"dateModified\":\"2021-06-09T18:57:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/infoecos.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sigue siendo alto el n\u00famero de casos activos en el distrito de Trenque Lauquen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/infoecos.com.ar\/#website\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"name\":\"Infoecos\",\"description\":\"Noticias de trenque lauquen y la zona\",\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"alternateName\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/infoecos.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/infoecos.com.ar\/#organization\",\"name\":\"Infoecos\",\"alternateName\":\"Noticias\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"width\":374,\"height\":90,\"caption\":\"Infoecos\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\",\"https:\/\/x.com\/infoecos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\",\"name\":\"Jorge Matheus\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sigue siendo alto el n\u00famero de casos activos en el distrito de Trenque Lauquen - Infoecos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/","og_locale":"es_ES","og_type":"article","og_title":"Sigue siendo alto el n\u00famero de casos activos en el distrito de Trenque Lauquen - Infoecos","og_description":"De los 486 casos activos, 409 pertenecen a la ciudad cabecera, 53 a Treinta de Agosto y 24 a Beruti: 43 se encuentran internados en el Hospital Municipal, uno (1) est\u00e1 en el Centro Extrahospitalario del ex Hotel Pailla Hu\u00e9 y 442 en sus domicilios particulares","og_url":"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/","og_site_name":"Infoecos","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063200290284","article_published_time":"2021-06-09T18:57:34+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/Acceso-23062017-1.jpg","type":"image\/jpeg"}],"author":"Jorge Matheus","twitter_card":"summary_large_image","twitter_creator":"@infoecos","twitter_site":"@infoecos","twitter_misc":{"Escrito por":"Jorge Matheus","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/#article","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/"},"author":{"name":"Jorge Matheus","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191"},"headline":"Sigue siendo alto el n\u00famero de casos activos en el distrito de Trenque Lauquen","datePublished":"2021-06-09T18:57:34+00:00","dateModified":"2021-06-09T18:57:34+00:00","mainEntityOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/"},"wordCount":265,"publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/#primaryimage"},"thumbnailUrl":"","keywords":["CORONAVIRUS"],"articleSection":["Noticia Secundaria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/","url":"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/","name":"Sigue siendo alto el n\u00famero de casos activos en el distrito de Trenque Lauquen - Infoecos","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/#primaryimage"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-06-09T18:57:34+00:00","dateModified":"2021-06-09T18:57:34+00:00","breadcrumb":{"@id":"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/infoecos.com.ar\/index.php\/sigue-siendo-alto-el-numero-de-casos-activos-en-el-distrito-de-trenque-lauquen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoecos.com.ar\/"},{"@type":"ListItem","position":2,"name":"Sigue siendo alto el n\u00famero de casos activos en el distrito de Trenque Lauquen"}]},{"@type":"WebSite","@id":"https:\/\/infoecos.com.ar\/#website","url":"https:\/\/infoecos.com.ar\/","name":"Infoecos","description":"Noticias de trenque lauquen y la zona","publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"alternateName":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoecos.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoecos.com.ar\/#organization","name":"Infoecos","alternateName":"Noticias","url":"https:\/\/infoecos.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","width":374,"height":90,"caption":"Infoecos"},"image":{"@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063200290284","https:\/\/x.com\/infoecos"]},{"@type":"Person","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191","name":"Jorge Matheus","url":"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/"}]}},"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","covernews-slider-full":"","covernews-slider-center":"","covernews-featured":"","covernews-medium":"","covernews-medium-square":""},"author_info":{"info":["Jorge Matheus"]},"category_info":"<a href=\"https:\/\/infoecos.com.ar\/index.php\/category\/noticia-secundaria\/\" rel=\"category tag\">Noticia Secundaria<\/a>","tag_info":"Noticia Secundaria","comment_count":"0","_links":{"self":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/79312"}],"collection":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=79312"}],"version-history":[{"count":1,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/79312\/revisions"}],"predecessor-version":[{"id":79314,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/79312\/revisions\/79314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=79312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=79312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=79312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}