{"id":79426,"date":"2021-06-11T01:06:43","date_gmt":"2021-06-11T04:06:43","guid":{"rendered":"http:\/\/infoecos.com.ar\/?p=79426"},"modified":"2021-06-12T01:31:17","modified_gmt":"2021-06-12T04:31:17","slug":"el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis","status":"publish","type":"post","link":"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/","title":{"rendered":"El 55% de las personas entre 55 y 59 a\u00f1os ya recibi\u00f3 la primera dosis"},"content":{"rendered":"\n<p>El 55% de las personas de entre 55 y 59 a\u00f1os ya recibi\u00f3 la primera dosis de vacunas contra el coronavirus, inform\u00f3 el Ministerio de Salud, a la vez que destac\u00f3 la cantidad de inoculantes que arribaron al pa\u00eds en los \u00faltimos d\u00edas, lo que permiti\u00f3 acelerar el plan de inmunizaci\u00f3n \u201chasta llegar al r\u00e9cord de 1.957.863 aplicaciones la semana pasada\u201d.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"460\" height=\"306\" src=\"http:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo-460x306.jpg\" alt=\"\" class=\"wp-image-77887\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo-460x306.jpg 460w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg 640w\" sizes=\"(max-width: 460px) 100vw, 460px\" \/><\/figure><\/div>\n\n\n\n<p>En cuanto a los mayores de 60 a\u00f1os, el 84,3 % ya recibi\u00f3 al menos una dosis y al desagregar por franjas etarias, el 85,7 % de las personas entre 60 a 69 se encuentra en la misma situaci\u00f3n \u201cque se replica en un 87,9 % y en un 79,4 % en aquellos que tienen entre 70 y 79 a\u00f1os y 80 a\u00f1os o m\u00e1s\u201d, informaron.<\/p>\n\n\n\n<p>Seg\u00fan la cartera sanitaria, una de cada dos personas de entre 55 y 59 a\u00f1os (el 55 %) ya recibi\u00f3 la primera dosis de vacuna contra esa enfermedad y tambi\u00e9n le fue aplicada al 45,3 % de la franja entre 50 y 54 a\u00f1os y al 33,2 % de las personas que tienen entre 45 a 49 a\u00f1os.<\/p>\n\n\n\n<p>La ministra de Salud,&nbsp;<strong>Carla Vizzotti,<\/strong>&nbsp;destac\u00f3 los resultados de la inmunizaci\u00f3n y se\u00f1al\u00f3 que \u201cse ve un impacto de la vacuna en la disminuci\u00f3n de la mortalidad, y al observar el total de fallecimientos, se evidencia una disminuci\u00f3n en la proporci\u00f3n de las personas mayores de 60 a\u00f1os\u201d.<\/p>\n\n\n\n<p>En ese sentido, durante el \u00faltimo encuentro del Consejo Federal de Salud (Cofesa) las y los ministros de Salud del pa\u00eds acordaron estrategias para ir a buscar activamente a la poblaci\u00f3n mayor de 60 a\u00f1os que por dificultades de acceso o temores, a\u00fan no fue vacunada.<\/p>\n\n\n\n<p>Dentro de los grupos priorizados, que conforman una poblaci\u00f3n de alrededor de 15 millones de personas, el 48,6 % de dosis aplicadas al 9 de junio correspond\u00eda a las personas de 60 a\u00f1os o m\u00e1s; y el 22,2 % al grupo de 18 a 59 a\u00f1os con factores de riesgo.<\/p>\n\n\n\n<p>El 16,4 % al personal de salud; el 10,4 % al personal estrat\u00e9gico; el 1 % a quienes tienen entre 50 a 59 a\u00f1os sin factores de riesgo; y el 0,9 % a las personas entre 40 y 49 a\u00f1os sin factores de riesgos, indic\u00f3 el Ministerio.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En cuanto a los mayores de 60 a\u00f1os, el 84,3 % ya recibi\u00f3 al menos una dosis y al desagregar por franjas etarias, el 85,7 % de las personas entre 60 a 69 se encuentra en la misma situaci\u00f3n \u201cque se replica en un 87,9 % y en un 79,4 % en aquellos que tienen entre 70 y 79 a\u00f1os y 80 a\u00f1os o m\u00e1s\u201d, informaron<\/p>\n","protected":false},"author":2,"featured_media":77887,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1643],"tags":[1785],"class_list":["post-79426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inferior16","tag-coronavirus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El 55% de las personas entre 55 y 59 a\u00f1os ya recibi\u00f3 la primera dosis - Infoecos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El 55% de las personas entre 55 y 59 a\u00f1os ya recibi\u00f3 la primera dosis - Infoecos\" \/>\n<meta property=\"og:description\" content=\"En cuanto a los mayores de 60 a\u00f1os, el 84,3 % ya recibi\u00f3 al menos una dosis y al desagregar por franjas etarias, el 85,7 % de las personas entre 60 a 69 se encuentra en la misma situaci\u00f3n \u201cque se replica en un 87,9 % y en un 79,4 % en aquellos que tienen entre 70 y 79 a\u00f1os y 80 a\u00f1os o m\u00e1s\u201d, informaron\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/\" \/>\n<meta property=\"og:site_name\" content=\"Infoecos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-11T04:06:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-12T04:31:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Matheus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infoecos\" \/>\n<meta name=\"twitter:site\" content=\"@infoecos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Matheus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/\"},\"author\":{\"name\":\"Jorge Matheus\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\"},\"headline\":\"El 55% de las personas entre 55 y 59 a\u00f1os ya recibi\u00f3 la primera dosis\",\"datePublished\":\"2021-06-11T04:06:43+00:00\",\"dateModified\":\"2021-06-12T04:31:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/\"},\"wordCount\":373,\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg\",\"keywords\":[\"CORONAVIRUS\"],\"articleSection\":[\"Bloque inferior - 16\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/\",\"name\":\"El 55% de las personas entre 55 y 59 a\u00f1os ya recibi\u00f3 la primera dosis - Infoecos\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg\",\"datePublished\":\"2021-06-11T04:06:43+00:00\",\"dateModified\":\"2021-06-12T04:31:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/#primaryimage\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg\",\"width\":640,\"height\":426},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/infoecos.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El 55% de las personas entre 55 y 59 a\u00f1os ya recibi\u00f3 la primera dosis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/infoecos.com.ar\/#website\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"name\":\"Infoecos\",\"description\":\"Noticias de trenque lauquen y la zona\",\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"alternateName\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/infoecos.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/infoecos.com.ar\/#organization\",\"name\":\"Infoecos\",\"alternateName\":\"Noticias\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"width\":374,\"height\":90,\"caption\":\"Infoecos\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\",\"https:\/\/x.com\/infoecos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\",\"name\":\"Jorge Matheus\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El 55% de las personas entre 55 y 59 a\u00f1os ya recibi\u00f3 la primera dosis - Infoecos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/","og_locale":"es_ES","og_type":"article","og_title":"El 55% de las personas entre 55 y 59 a\u00f1os ya recibi\u00f3 la primera dosis - Infoecos","og_description":"En cuanto a los mayores de 60 a\u00f1os, el 84,3 % ya recibi\u00f3 al menos una dosis y al desagregar por franjas etarias, el 85,7 % de las personas entre 60 a 69 se encuentra en la misma situaci\u00f3n \u201cque se replica en un 87,9 % y en un 79,4 % en aquellos que tienen entre 70 y 79 a\u00f1os y 80 a\u00f1os o m\u00e1s\u201d, informaron","og_url":"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/","og_site_name":"Infoecos","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063200290284","article_published_time":"2021-06-11T04:06:43+00:00","article_modified_time":"2021-06-12T04:31:17+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg","type":"image\/jpeg"}],"author":"Jorge Matheus","twitter_card":"summary_large_image","twitter_creator":"@infoecos","twitter_site":"@infoecos","twitter_misc":{"Escrito por":"Jorge Matheus","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/#article","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/"},"author":{"name":"Jorge Matheus","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191"},"headline":"El 55% de las personas entre 55 y 59 a\u00f1os ya recibi\u00f3 la primera dosis","datePublished":"2021-06-11T04:06:43+00:00","dateModified":"2021-06-12T04:31:17+00:00","mainEntityOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/"},"wordCount":373,"publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg","keywords":["CORONAVIRUS"],"articleSection":["Bloque inferior - 16"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/","url":"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/","name":"El 55% de las personas entre 55 y 59 a\u00f1os ya recibi\u00f3 la primera dosis - Infoecos","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/#primaryimage"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg","datePublished":"2021-06-11T04:06:43+00:00","dateModified":"2021-06-12T04:31:17+00:00","breadcrumb":{"@id":"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/#primaryimage","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg","width":640,"height":426},{"@type":"BreadcrumbList","@id":"https:\/\/infoecos.com.ar\/index.php\/el-55-de-las-personas-entre-55-y-59-anos-ya-recibio-la-primera-dosis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoecos.com.ar\/"},{"@type":"ListItem","position":2,"name":"El 55% de las personas entre 55 y 59 a\u00f1os ya recibi\u00f3 la primera dosis"}]},{"@type":"WebSite","@id":"https:\/\/infoecos.com.ar\/#website","url":"https:\/\/infoecos.com.ar\/","name":"Infoecos","description":"Noticias de trenque lauquen y la zona","publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"alternateName":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoecos.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoecos.com.ar\/#organization","name":"Infoecos","alternateName":"Noticias","url":"https:\/\/infoecos.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","width":374,"height":90,"caption":"Infoecos"},"image":{"@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063200290284","https:\/\/x.com\/infoecos"]},{"@type":"Person","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191","name":"Jorge Matheus","url":"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/"}]}},"featured_image_urls":{"full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg",640,426,false],"thumbnail":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo-150x150.jpg",150,150,true],"medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo-460x306.jpg",460,306,true],"medium_large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg",640,426,false],"large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg",640,426,false],"1536x1536":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg",640,426,false],"2048x2048":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg",640,426,false],"covernews-slider-full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg",640,426,false],"covernews-slider-center":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg",640,426,false],"covernews-featured":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg",640,426,false],"covernews-medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo-640x380.jpg",540,321,true],"covernews-medium-square":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/05\/vacunacionpehuajo.jpg",376,250,false]},"author_info":{"info":["Jorge Matheus"]},"category_info":"<a href=\"https:\/\/infoecos.com.ar\/index.php\/category\/inferior16\/\" rel=\"category tag\">Bloque inferior - 16<\/a>","tag_info":"Bloque inferior - 16","comment_count":"0","_links":{"self":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/79426"}],"collection":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=79426"}],"version-history":[{"count":1,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/79426\/revisions"}],"predecessor-version":[{"id":79427,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/79426\/revisions\/79427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media\/77887"}],"wp:attachment":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=79426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=79426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=79426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}