{"id":79905,"date":"2021-06-22T02:23:43","date_gmt":"2021-06-22T05:23:43","guid":{"rendered":"http:\/\/infoecos.com.ar\/?p=79905"},"modified":"2021-06-23T02:56:34","modified_gmt":"2021-06-23T05:56:34","slug":"altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus","status":"publish","type":"post","link":"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/","title":{"rendered":"Altas multas en Bragado para quienes incumplan con las medidas dispuestas por el coronavirus"},"content":{"rendered":"\n<p>La Municipalidad de Bragado comunic\u00f3 oficialmente&nbsp;la promulgaci\u00f3n de la Ordenanza 5371\/21&nbsp;que establece las&nbsp;nuevas normativas y sanciones&nbsp;que rigen en Bragado ante casos de incumplimiento del aislamiento social, preventivo y obligatorio.&nbsp;Fija altas multas por la organizaci\u00f3n o participaci\u00f3n en reuniones sociales, el no uso (o uso incorrecto) del cubrebocas y tambi\u00e9n por todo lo que est\u00e1 relacionado con infracciones de las medidas preventivas y protocolos.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"http:\/\/infoecos.com.ar\/wp-content\/uploads\/Bragado-Municipalidad.jpg\" alt=\"Bragado - Edificio Municipal\" class=\"wp-image-21928\"\/><figcaption>Bragado &#8211; Edificio Municipal<\/figcaption><\/figure><\/div>\n\n\n\n<p>De acuerdo a lo dispuesto, ante situaciones de&nbsp;violaci\u00f3n del aislamiento obligatorio&nbsp;se aplicar\u00e1n sanciones de&nbsp;entre $3970 y $23.820, mientras que a aquellas personas&nbsp;no esenciales que circulen en horarios no permitidos&nbsp;podr\u00edan caberle multas de&nbsp;hasta $39.700.<\/p>\n\n\n\n<p>Quienes no usen tapabocas tendr\u00e1n que pagar entre $3970 y $39.700; y el&nbsp;incumplimiento de las medidas de prevenci\u00f3n para las actividades deportivas, art\u00edsticas, culturales, religiosas o sociales&nbsp;acarrear\u00e1 sanciones de&nbsp;entre $7940 y $23.820, e incluso la clausura de los locales hasta 60 d\u00edas.<\/p>\n\n\n\n<p>En lo que respecta a las&nbsp;reuniones sociales&nbsp;en espacios p\u00fablicos o privados, habr\u00e1 multas de&nbsp;entre $15.880 y $79.400, las cuales aplicar\u00e1n tanto en el organizador, como en los asistentes y la persona que facilite la propiedad.<\/p>\n\n\n\n<p>La Ordenanza tambi\u00e9n prev\u00e9 sanciones especiales para los&nbsp;gastron\u00f3micos que incumplan la normativa. Fija multas&nbsp;de $3.970 a 39.700&nbsp;y tambi\u00e9n la clausura del lugar de hasta 90 d\u00edas.<\/p>\n\n\n\n<p><strong>Fuente: bragadotv.com.ar<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fija altas multas por la organizaci\u00f3n o participaci\u00f3n en reuniones sociales, el no uso (o uso incorrecto) del cubrebocas y tambi\u00e9n por todo lo que est\u00e1 relacionado con infracciones de las medidas preventivas y protocolos<\/p>\n","protected":false},"author":2,"featured_media":59327,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[200],"tags":[3964],"class_list":["post-79905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inferior8","tag-se-promulgo-una-ordenanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Altas multas en Bragado para quienes incumplan con las medidas dispuestas por el coronavirus - Infoecos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Altas multas en Bragado para quienes incumplan con las medidas dispuestas por el coronavirus - Infoecos\" \/>\n<meta property=\"og:description\" content=\"Fija altas multas por la organizaci\u00f3n o participaci\u00f3n en reuniones sociales, el no uso (o uso incorrecto) del cubrebocas y tambi\u00e9n por todo lo que est\u00e1 relacionado con infracciones de las medidas preventivas y protocolos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"Infoecos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-22T05:23:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-23T05:56:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1706\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Matheus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infoecos\" \/>\n<meta name=\"twitter:site\" content=\"@infoecos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Matheus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/\"},\"author\":{\"name\":\"Jorge Matheus\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\"},\"headline\":\"Altas multas en Bragado para quienes incumplan con las medidas dispuestas por el coronavirus\",\"datePublished\":\"2021-06-22T05:23:43+00:00\",\"dateModified\":\"2021-06-23T05:56:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/\"},\"wordCount\":264,\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL.jpg\",\"keywords\":[\"SE PROMULG\u00d3 UNA ORDENANZA\"],\"articleSection\":[\"Bloque inferior - 8\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/\",\"name\":\"Altas multas en Bragado para quienes incumplan con las medidas dispuestas por el coronavirus - Infoecos\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL.jpg\",\"datePublished\":\"2021-06-22T05:23:43+00:00\",\"dateModified\":\"2021-06-23T05:56:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/#primaryimage\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL.jpg\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL.jpg\",\"width\":1706,\"height\":960,\"caption\":\"Bragado - Edificio Municipal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/infoecos.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Altas multas en Bragado para quienes incumplan con las medidas dispuestas por el coronavirus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/infoecos.com.ar\/#website\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"name\":\"Infoecos\",\"description\":\"Noticias de trenque lauquen y la zona\",\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"alternateName\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/infoecos.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/infoecos.com.ar\/#organization\",\"name\":\"Infoecos\",\"alternateName\":\"Noticias\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"width\":374,\"height\":90,\"caption\":\"Infoecos\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\",\"https:\/\/x.com\/infoecos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\",\"name\":\"Jorge Matheus\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Altas multas en Bragado para quienes incumplan con las medidas dispuestas por el coronavirus - Infoecos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/","og_locale":"es_ES","og_type":"article","og_title":"Altas multas en Bragado para quienes incumplan con las medidas dispuestas por el coronavirus - Infoecos","og_description":"Fija altas multas por la organizaci\u00f3n o participaci\u00f3n en reuniones sociales, el no uso (o uso incorrecto) del cubrebocas y tambi\u00e9n por todo lo que est\u00e1 relacionado con infracciones de las medidas preventivas y protocolos","og_url":"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/","og_site_name":"Infoecos","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063200290284","article_published_time":"2021-06-22T05:23:43+00:00","article_modified_time":"2021-06-23T05:56:34+00:00","og_image":[{"width":1706,"height":960,"url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL.jpg","type":"image\/jpeg"}],"author":"Jorge Matheus","twitter_card":"summary_large_image","twitter_creator":"@infoecos","twitter_site":"@infoecos","twitter_misc":{"Escrito por":"Jorge Matheus","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/#article","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/"},"author":{"name":"Jorge Matheus","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191"},"headline":"Altas multas en Bragado para quienes incumplan con las medidas dispuestas por el coronavirus","datePublished":"2021-06-22T05:23:43+00:00","dateModified":"2021-06-23T05:56:34+00:00","mainEntityOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/"},"wordCount":264,"publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL.jpg","keywords":["SE PROMULG\u00d3 UNA ORDENANZA"],"articleSection":["Bloque inferior - 8"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/","url":"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/","name":"Altas multas en Bragado para quienes incumplan con las medidas dispuestas por el coronavirus - Infoecos","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/#primaryimage"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL.jpg","datePublished":"2021-06-22T05:23:43+00:00","dateModified":"2021-06-23T05:56:34+00:00","breadcrumb":{"@id":"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/#primaryimage","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL.jpg","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL.jpg","width":1706,"height":960,"caption":"Bragado - Edificio Municipal"},{"@type":"BreadcrumbList","@id":"https:\/\/infoecos.com.ar\/index.php\/altas-multas-en-bragado-para-quienes-incumplan-con-las-medidas-dispuestas-por-el-coronavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoecos.com.ar\/"},{"@type":"ListItem","position":2,"name":"Altas multas en Bragado para quienes incumplan con las medidas dispuestas por el coronavirus"}]},{"@type":"WebSite","@id":"https:\/\/infoecos.com.ar\/#website","url":"https:\/\/infoecos.com.ar\/","name":"Infoecos","description":"Noticias de trenque lauquen y la zona","publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"alternateName":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoecos.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoecos.com.ar\/#organization","name":"Infoecos","alternateName":"Noticias","url":"https:\/\/infoecos.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","width":374,"height":90,"caption":"Infoecos"},"image":{"@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063200290284","https:\/\/x.com\/infoecos"]},{"@type":"Person","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191","name":"Jorge Matheus","url":"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/"}]}},"featured_image_urls":{"full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL.jpg",1706,960,false],"thumbnail":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL-150x150.jpg",150,150,true],"medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL-460x259.jpg",460,259,true],"medium_large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL-768x432.jpg",640,360,true],"large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL-920x518.jpg",640,360,true],"1536x1536":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL-1536x864.jpg",1536,864,true],"2048x2048":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL.jpg",1706,960,false],"covernews-slider-full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL-1536x960.jpg",1115,697,true],"covernews-slider-center":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL-936x897.jpg",522,500,true],"covernews-featured":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL-1024x576.jpg",1024,576,true],"covernews-medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL-720x380.jpg",540,285,true],"covernews-medium-square":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/BRAGADO-EDIFICIO-MUNICIPAL-675x450.jpg",375,250,true]},"author_info":{"info":["Jorge Matheus"]},"category_info":"<a href=\"https:\/\/infoecos.com.ar\/index.php\/category\/inferior8\/\" rel=\"category tag\">Bloque inferior - 8<\/a>","tag_info":"Bloque inferior - 8","comment_count":"0","_links":{"self":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/79905"}],"collection":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=79905"}],"version-history":[{"count":2,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/79905\/revisions"}],"predecessor-version":[{"id":80006,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/79905\/revisions\/80006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media\/59327"}],"wp:attachment":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=79905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=79905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=79905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}