{"id":80433,"date":"2021-06-29T19:19:50","date_gmt":"2021-06-29T22:19:50","guid":{"rendered":"http:\/\/infoecos.com.ar\/?p=80433"},"modified":"2021-07-01T03:25:45","modified_gmt":"2021-07-01T06:25:45","slug":"comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen","status":"publish","type":"post","link":"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/","title":{"rendered":"Comenzaron los trabajos de colocaci\u00f3n del nuevo piso en la Plaza San Mart\u00edn de Trenque Lauquen"},"content":{"rendered":"\n<p>La municipalidad de Trenque Lauquen comenz\u00f3 este martes los trabajos de colocaci\u00f3n del nuevo piso en la Plaza San Mart\u00edn, donde previamente se hab\u00eda realizado el trabajo de implantaci\u00f3n y compactaci\u00f3n de la tosca proveniente de una cantera de Santa Rosa, La Pampa, en el marco del proyecto de remodelaci\u00f3n de este espacio p\u00fablico.<\/p>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"460\" height=\"307\" src=\"http:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-2-460x307.jpg\" alt=\"\" class=\"wp-image-80434\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-2-460x307.jpg 460w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-2-768x512.jpg 768w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-2-675x450.jpg 675w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-2.jpg 852w\" sizes=\"(max-width: 460px) 100vw, 460px\" \/><figcaption>Plaza San Mart\u00edn<\/figcaption><\/figure><\/div>\n\n\n\n<p>\u201cDespu\u00e9s de algunos contratiempos y demoras llegaron el lunes las cinco personas encargadas de colocar el piso y este martes bien temprano empezaron con los trabajos\u201d, coment\u00f3 el subsecretario de Gesti\u00f3n de Obras P\u00fablicas del Municipio, Arquitecto Cristian Rabasa.<\/p>\n\n\n\n<p>\u201cHab\u00edan coordinado con el director de la obra lo relacionado con la arena y los otros elementos que necesitaban, y arrancaron a buen ritmo, adem\u00e1s el clima acompa\u00f1a a pesar de la helada\u201d, precis\u00f3 el funcionario.<\/p>\n\n\n\n<p>Acerca de las tareas realizadas hasta el momento, Rabasa se\u00f1al\u00f3 que \u201cel trabajo m\u00e1s grande que hizo la Municipalidad fue traer la tosca, compactarla y darle el nivel que ten\u00eda que tener para que la colocaci\u00f3n del piso sea m\u00e1s f\u00e1cil y r\u00e1pida\u201d.<\/p>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"460\" height=\"307\" src=\"http:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-3-460x307.jpg\" alt=\"\" class=\"wp-image-80435\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-3-460x307.jpg 460w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-3-768x512.jpg 768w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-3-675x450.jpg 675w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-3.jpg 852w\" sizes=\"(max-width: 460px) 100vw, 460px\" \/><figcaption>Plaza San Mart\u00edn (veredas)<\/figcaption><\/figure><\/div>\n\n\n\n<p>\u201cEl capataz nos dijo que el nivel est\u00e1 muy bien aunque con la capa de arena gruesa ellos pueden salvar posibles imperfecciones, hay que tener en cuenta que al estar bien nivelado se acelera el proceso de ellos tambi\u00e9n\u201d, explic\u00f3.<\/p>\n\n\n\n<p>Asimismo coment\u00f3 que \u201cel trabajo parece sencillo pero lo que sucede es que esta gente tiene mucha experiencia\u201d y acerca del tipo de trabajo que realizan, Rabasa explic\u00f3 que \u201csiguen l\u00edneas con hilos y niveles que van tomando, se coordinan para la colocaci\u00f3n de los pisos de dos en dos; primero desparraman la arena gruesa y luego manualmente van corrigiendo las imperfecciones, despu\u00e9s hacen una peque\u00f1a compactaci\u00f3n sobre la arena gruesa, luego le tiran arena fina y&nbsp; hacen una segunda compactaci\u00f3n y es el trabajo final\u201d.<\/p>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"460\" height=\"307\" src=\"http:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-460x307.jpg\" alt=\"\" class=\"wp-image-80436\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-460x307.jpg 460w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-768x512.jpg 768w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-675x450.jpg 675w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin.jpg 852w\" sizes=\"(max-width: 460px) 100vw, 460px\" \/><figcaption>Plaza San Mart\u00edn (veredas)<\/figcaption><\/figure><\/div>\n\n\n\n<p>En cuanto a futuros trabajos, el funcionario se\u00f1al\u00f3 que \u201cvan a quedar colocar unos bordes de hormig\u00f3n que van contra el espacio del c\u00e9sped que todav\u00eda no han llegado, pero no es problema para la colocaci\u00f3n del piso porque se colocan al final\u201d.<\/p>\n\n\n\n<p>Consultado sobre el tiempo estimado para la finalizaci\u00f3n de la obra de colocaci\u00f3n del piso, Rabasa coment\u00f3: \u201cSi nos trata bien el clima, el Covid-19 (por posibles casos positivos y aislamiento del personal) y otras cuestiones que puedan pasar, calculamos que en un mes y medio tiene que estar listo el trabajo\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Llegaron el lunes las cinco personas encargadas de colocar el piso y este martes bien temprano empezaron con los trabajos\u201d, coment\u00f3 el Arquitecto Cristian Rabasa<\/p>\n","protected":false},"author":2,"featured_media":80437,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[2506],"class_list":["post-80433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inferior6","tag-este-martes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comenzaron los trabajos de colocaci\u00f3n del nuevo piso en la Plaza San Mart\u00edn de Trenque Lauquen - Infoecos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comenzaron los trabajos de colocaci\u00f3n del nuevo piso en la Plaza San Mart\u00edn de Trenque Lauquen - Infoecos\" \/>\n<meta property=\"og:description\" content=\"Llegaron el lunes las cinco personas encargadas de colocar el piso y este martes bien temprano empezaron con los trabajos\u201d, coment\u00f3 el Arquitecto Cristian Rabasa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/\" \/>\n<meta property=\"og:site_name\" content=\"Infoecos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-29T22:19:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-01T06:25:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"852\" \/>\n\t<meta property=\"og:image:height\" content=\"568\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Matheus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infoecos\" \/>\n<meta name=\"twitter:site\" content=\"@infoecos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Matheus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/\"},\"author\":{\"name\":\"Jorge Matheus\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\"},\"headline\":\"Comenzaron los trabajos de colocaci\u00f3n del nuevo piso en la Plaza San Mart\u00edn de Trenque Lauquen\",\"datePublished\":\"2021-06-29T22:19:50+00:00\",\"dateModified\":\"2021-07-01T06:25:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/\"},\"wordCount\":460,\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4.jpg\",\"keywords\":[\"este martes\"],\"articleSection\":[\"Bloque inferior - 6\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/\",\"name\":\"Comenzaron los trabajos de colocaci\u00f3n del nuevo piso en la Plaza San Mart\u00edn de Trenque Lauquen - Infoecos\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4.jpg\",\"datePublished\":\"2021-06-29T22:19:50+00:00\",\"dateModified\":\"2021-07-01T06:25:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/#primaryimage\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4.jpg\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4.jpg\",\"width\":852,\"height\":568},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/infoecos.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comenzaron los trabajos de colocaci\u00f3n del nuevo piso en la Plaza San Mart\u00edn de Trenque Lauquen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/infoecos.com.ar\/#website\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"name\":\"Infoecos\",\"description\":\"Noticias de trenque lauquen y la zona\",\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"alternateName\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/infoecos.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/infoecos.com.ar\/#organization\",\"name\":\"Infoecos\",\"alternateName\":\"Noticias\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"width\":374,\"height\":90,\"caption\":\"Infoecos\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\",\"https:\/\/x.com\/infoecos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\",\"name\":\"Jorge Matheus\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comenzaron los trabajos de colocaci\u00f3n del nuevo piso en la Plaza San Mart\u00edn de Trenque Lauquen - Infoecos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/","og_locale":"es_ES","og_type":"article","og_title":"Comenzaron los trabajos de colocaci\u00f3n del nuevo piso en la Plaza San Mart\u00edn de Trenque Lauquen - Infoecos","og_description":"Llegaron el lunes las cinco personas encargadas de colocar el piso y este martes bien temprano empezaron con los trabajos\u201d, coment\u00f3 el Arquitecto Cristian Rabasa","og_url":"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/","og_site_name":"Infoecos","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063200290284","article_published_time":"2021-06-29T22:19:50+00:00","article_modified_time":"2021-07-01T06:25:45+00:00","og_image":[{"width":852,"height":568,"url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4.jpg","type":"image\/jpeg"}],"author":"Jorge Matheus","twitter_card":"summary_large_image","twitter_creator":"@infoecos","twitter_site":"@infoecos","twitter_misc":{"Escrito por":"Jorge Matheus","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/#article","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/"},"author":{"name":"Jorge Matheus","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191"},"headline":"Comenzaron los trabajos de colocaci\u00f3n del nuevo piso en la Plaza San Mart\u00edn de Trenque Lauquen","datePublished":"2021-06-29T22:19:50+00:00","dateModified":"2021-07-01T06:25:45+00:00","mainEntityOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/"},"wordCount":460,"publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4.jpg","keywords":["este martes"],"articleSection":["Bloque inferior - 6"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/","url":"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/","name":"Comenzaron los trabajos de colocaci\u00f3n del nuevo piso en la Plaza San Mart\u00edn de Trenque Lauquen - Infoecos","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/#primaryimage"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4.jpg","datePublished":"2021-06-29T22:19:50+00:00","dateModified":"2021-07-01T06:25:45+00:00","breadcrumb":{"@id":"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/#primaryimage","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4.jpg","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4.jpg","width":852,"height":568},{"@type":"BreadcrumbList","@id":"https:\/\/infoecos.com.ar\/index.php\/comenzaron-los-trabajos-de-colocacion-del-nuevo-piso-en-la-plaza-san-martin-de-trenque-lauquen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoecos.com.ar\/"},{"@type":"ListItem","position":2,"name":"Comenzaron los trabajos de colocaci\u00f3n del nuevo piso en la Plaza San Mart\u00edn de Trenque Lauquen"}]},{"@type":"WebSite","@id":"https:\/\/infoecos.com.ar\/#website","url":"https:\/\/infoecos.com.ar\/","name":"Infoecos","description":"Noticias de trenque lauquen y la zona","publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"alternateName":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoecos.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoecos.com.ar\/#organization","name":"Infoecos","alternateName":"Noticias","url":"https:\/\/infoecos.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","width":374,"height":90,"caption":"Infoecos"},"image":{"@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063200290284","https:\/\/x.com\/infoecos"]},{"@type":"Person","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191","name":"Jorge Matheus","url":"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/"}]}},"featured_image_urls":{"full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4.jpg",852,568,false],"thumbnail":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4-150x150.jpg",150,150,true],"medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4-460x307.jpg",460,307,true],"medium_large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4-768x512.jpg",640,427,true],"large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4.jpg",640,427,false],"1536x1536":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4.jpg",852,568,false],"2048x2048":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4.jpg",852,568,false],"covernews-slider-full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4.jpg",852,568,false],"covernews-slider-center":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4.jpg",750,500,false],"covernews-featured":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4.jpg",852,568,false],"covernews-medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4-720x380.jpg",540,285,true],"covernews-medium-square":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/06\/Trabajos-en-Plaza-San-Martin-4-675x450.jpg",375,250,true]},"author_info":{"info":["Jorge Matheus"]},"category_info":"<a href=\"https:\/\/infoecos.com.ar\/index.php\/category\/inferior6\/\" rel=\"category tag\">Bloque inferior - 6<\/a>","tag_info":"Bloque inferior - 6","comment_count":"0","_links":{"self":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/80433"}],"collection":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=80433"}],"version-history":[{"count":1,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/80433\/revisions"}],"predecessor-version":[{"id":80438,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/80433\/revisions\/80438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media\/80437"}],"wp:attachment":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=80433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=80433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=80433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}