{"id":87919,"date":"2021-10-12T16:12:41","date_gmt":"2021-10-12T19:12:41","guid":{"rendered":"http:\/\/infoecos.com.ar\/?p=87919"},"modified":"2021-10-12T16:12:42","modified_gmt":"2021-10-12T19:12:42","slug":"torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos","status":"publish","type":"post","link":"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/","title":{"rendered":"Torchio anunci\u00f3 aumento salarial para el mes de Octubre y un bono complementario de 7.000 pesos"},"content":{"rendered":"\n<p>El Intendente de Carlos Casares, Walter Torchio anunci\u00f3 un aumento salarial para el mes de octubre del 5 % llegando al 40,39% en lo que va del a\u00f1o. A su vez se incorpora un bono complementario de $ 7.000 para los empleados municipales. No ser\u00e1 percibido por Subsecretarios, Secretarios, Intendente y Concejales. <\/p>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"460\" height=\"259\" src=\"http:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5-460x259.jpg\" alt=\"\" class=\"wp-image-87920\" srcset=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5-460x259.jpg 460w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5-920x518.jpg 920w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5-768x432.jpg 768w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5-1024x576.jpg 1024w, https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5.jpg 1280w\" sizes=\"(max-width: 460px) 100vw, 460px\" \/><figcaption>Torchio analizando el aumento<\/figcaption><\/figure><\/div>\n\n\n\n<p>La comunicaci\u00f3n la hizo efectiva luego de haber mantenido un encuentro con los Secretarios, Ingeniero Daniel Stadnik, Dr. Marcelo Agradi, y Contador Christian Massone,<\/p>\n\n\n\n<p>Dicho bono estar\u00e1 disponible para este viernes 15.&nbsp;<\/p>\n\n\n\n<p>En el 2.021 ya se hab\u00eda procedido de manera adicional a subir la antig\u00fcedad, aumento por presentismo, un bono en marzo, y distintas bonificaciones dentro del \u00e1rea de Salud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No ser\u00e1 percibido por Subsecretarios, Secretarios, Intendente y Concejales<\/p>\n","protected":false},"author":2,"featured_media":87920,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[5421],"class_list":["post-87919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c3nota2","tag-el-bono-disponible-a-partir-del-15"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Torchio anunci\u00f3 aumento salarial para el mes de Octubre y un bono complementario de 7.000 pesos - Infoecos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Torchio anunci\u00f3 aumento salarial para el mes de Octubre y un bono complementario de 7.000 pesos - Infoecos\" \/>\n<meta property=\"og:description\" content=\"No ser\u00e1 percibido por Subsecretarios, Secretarios, Intendente y Concejales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/\" \/>\n<meta property=\"og:site_name\" content=\"Infoecos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-12T19:12:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-12T19:12:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Matheus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infoecos\" \/>\n<meta name=\"twitter:site\" content=\"@infoecos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Matheus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/\"},\"author\":{\"name\":\"Jorge Matheus\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\"},\"headline\":\"Torchio anunci\u00f3 aumento salarial para el mes de Octubre y un bono complementario de 7.000 pesos\",\"datePublished\":\"2021-10-12T19:12:41+00:00\",\"dateModified\":\"2021-10-12T19:12:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/\"},\"wordCount\":130,\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5.jpg\",\"keywords\":[\"EL BONO DISPONIBLE A PARTIR DEL 15\"],\"articleSection\":[\"C3 N2\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/\",\"name\":\"Torchio anunci\u00f3 aumento salarial para el mes de Octubre y un bono complementario de 7.000 pesos - Infoecos\",\"isPartOf\":{\"@id\":\"https:\/\/infoecos.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5.jpg\",\"datePublished\":\"2021-10-12T19:12:41+00:00\",\"dateModified\":\"2021-10-12T19:12:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/#primaryimage\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5.jpg\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/infoecos.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Torchio anunci\u00f3 aumento salarial para el mes de Octubre y un bono complementario de 7.000 pesos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/infoecos.com.ar\/#website\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"name\":\"Infoecos\",\"description\":\"Noticias de trenque lauquen y la zona\",\"publisher\":{\"@id\":\"https:\/\/infoecos.com.ar\/#organization\"},\"alternateName\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/infoecos.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/infoecos.com.ar\/#organization\",\"name\":\"Infoecos\",\"alternateName\":\"Noticias\",\"url\":\"https:\/\/infoecos.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"contentUrl\":\"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png\",\"width\":374,\"height\":90,\"caption\":\"Infoecos\"},\"image\":{\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063200290284\",\"https:\/\/x.com\/infoecos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191\",\"name\":\"Jorge Matheus\",\"url\":\"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Torchio anunci\u00f3 aumento salarial para el mes de Octubre y un bono complementario de 7.000 pesos - Infoecos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/","og_locale":"es_ES","og_type":"article","og_title":"Torchio anunci\u00f3 aumento salarial para el mes de Octubre y un bono complementario de 7.000 pesos - Infoecos","og_description":"No ser\u00e1 percibido por Subsecretarios, Secretarios, Intendente y Concejales","og_url":"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/","og_site_name":"Infoecos","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063200290284","article_published_time":"2021-10-12T19:12:41+00:00","article_modified_time":"2021-10-12T19:12:42+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5.jpg","type":"image\/jpeg"}],"author":"Jorge Matheus","twitter_card":"summary_large_image","twitter_creator":"@infoecos","twitter_site":"@infoecos","twitter_misc":{"Escrito por":"Jorge Matheus","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/#article","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/"},"author":{"name":"Jorge Matheus","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191"},"headline":"Torchio anunci\u00f3 aumento salarial para el mes de Octubre y un bono complementario de 7.000 pesos","datePublished":"2021-10-12T19:12:41+00:00","dateModified":"2021-10-12T19:12:42+00:00","mainEntityOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/"},"wordCount":130,"publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5.jpg","keywords":["EL BONO DISPONIBLE A PARTIR DEL 15"],"articleSection":["C3 N2"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/","url":"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/","name":"Torchio anunci\u00f3 aumento salarial para el mes de Octubre y un bono complementario de 7.000 pesos - Infoecos","isPartOf":{"@id":"https:\/\/infoecos.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/#primaryimage"},"image":{"@id":"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/#primaryimage"},"thumbnailUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5.jpg","datePublished":"2021-10-12T19:12:41+00:00","dateModified":"2021-10-12T19:12:42+00:00","breadcrumb":{"@id":"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/#primaryimage","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5.jpg","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/infoecos.com.ar\/index.php\/torchio-anuncio-aumento-salarial-para-el-mes-de-octubre-y-un-bono-complementario-de-7-000-pesos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoecos.com.ar\/"},{"@type":"ListItem","position":2,"name":"Torchio anunci\u00f3 aumento salarial para el mes de Octubre y un bono complementario de 7.000 pesos"}]},{"@type":"WebSite","@id":"https:\/\/infoecos.com.ar\/#website","url":"https:\/\/infoecos.com.ar\/","name":"Infoecos","description":"Noticias de trenque lauquen y la zona","publisher":{"@id":"https:\/\/infoecos.com.ar\/#organization"},"alternateName":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoecos.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoecos.com.ar\/#organization","name":"Infoecos","alternateName":"Noticias","url":"https:\/\/infoecos.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","contentUrl":"https:\/\/infoecos.com.ar\/wp-content\/uploads\/2024\/03\/cropped-logo.png","width":374,"height":90,"caption":"Infoecos"},"image":{"@id":"https:\/\/infoecos.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063200290284","https:\/\/x.com\/infoecos"]},{"@type":"Person","@id":"https:\/\/infoecos.com.ar\/#\/schema\/person\/8f5ace5ce73b4b4aac4b7245aee6f191","name":"Jorge Matheus","url":"https:\/\/infoecos.com.ar\/index.php\/author\/jomatheus\/"}]}},"featured_image_urls":{"full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5.jpg",1280,720,false],"thumbnail":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5-150x150.jpg",150,150,true],"medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5-460x259.jpg",460,259,true],"medium_large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5-768x432.jpg",640,360,true],"large":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5-920x518.jpg",640,360,true],"1536x1536":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5.jpg",1280,720,false],"2048x2048":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5.jpg",1280,720,false],"covernews-slider-full":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5.jpg",1115,627,false],"covernews-slider-center":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5-936x720.jpg",650,500,true],"covernews-featured":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5-1024x576.jpg",1024,576,true],"covernews-medium":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5-720x380.jpg",540,285,true],"covernews-medium-square":["https:\/\/infoecos.com.ar\/wp-content\/uploads\/2021\/10\/Reunion-Aumento-5-675x450.jpg",375,250,true]},"author_info":{"info":["Jorge Matheus"]},"category_info":"<a href=\"https:\/\/infoecos.com.ar\/index.php\/category\/c3nota2\/\" rel=\"category tag\">C3 N2<\/a>","tag_info":"C3 N2","comment_count":"0","_links":{"self":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/87919"}],"collection":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=87919"}],"version-history":[{"count":1,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/87919\/revisions"}],"predecessor-version":[{"id":87921,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/87919\/revisions\/87921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media\/87920"}],"wp:attachment":[{"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=87919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=87919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoecos.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=87919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}